{"id":12989,"date":"2019-06-19T20:28:30","date_gmt":"2019-06-19T20:28:30","guid":{"rendered":"https:\/\/beyondtype2.org\/resources\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/"},"modified":"2019-06-19T20:28:30","modified_gmt":"2019-06-19T20:28:30","slug":"esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad","status":"publish","type":"resources","link":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/","title":{"rendered":"&#8216;Esto no me pasa a mi&#8217;: una nueva perspectiva sobre CAD"},"content":{"rendered":"<p><span style=\"font-size: 48px; font-weight: bold; letter-spacing: -0.0415625em; font-family: 'Gotham SSm A', 'Gotham SSm B';\">Historia Real<\/span><\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>No me siento como un idiota, ni un inepto, ni estoy completamente loco &hellip; pero as&iacute; es como imaginaba que la gente me tratar&iacute;a cuando entr&eacute; en cetoacidosis diab&eacute;tica (CAD) no hace mucho.<\/p>\n<p>En los 27 a&ntilde;os que he vivido con diabetes tipo 1 &nbsp;no hay letras m&aacute;s aterradoras que la temida C-A-D. Cetoacidosis diab&eacute;tica. Hablamos de ello como si fuera el coco o un mito urbano y solo en voz baja como si estuvi&eacute;ramos sentados alrededor de una fogata contando historias de miedo. Y a pesar de todos y mis mejores esfuerzos, me sucedi&oacute;.<\/p>\n<p>Me consideraba en excelentes condiciones, ten&iacute;a una A1C de alrededor de 6,0 y &iexcl;me sent&iacute;a bien! Cambi&eacute; el sitio de infusi&oacute;n de mi bomba de insulina una noche y no pens&eacute; en nada, como siempre. Durante las siguientes 24 horas, me di cuenta de que ten&iacute;a un &laquo;sitio malo&raquo; porque la cantidad de insulina que normalmente habr&iacute;a hecho que mi glucosa en sangre volviera a un rango normal no parec&iacute;a estar funcionando. As&iacute; que simplemente me aferr&eacute; a la bomba y apliqu&eacute; m&aacute;s insulina de lo normal. Error de novato, &iquest;verdad?<\/p>\n<\/div>\n<\/div>\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Durante dos d&iacute;as seguidos, luch&eacute; contra el aumento de los niveles de glucosa en sangre y me volv&iacute; tan obstinado que no pod&iacute;a ver lo que lentamente estaba sucediendo. Estaba promediando lecturas de glucosa en sangre apenas por encima de los 200 y aunque eso no parec&iacute;a ser demasiado alto, fue el tiempo que pas&eacute; con la glucosa elevada lo comenz&oacute; a preocuparme. No beber suficiente l&iacute;quido ni electrolitos junto con la fatiga que sent&iacute;a comenz&oacute; a cobrarme factura.<\/p>\n<h2>Una batalla perdida<\/h2>\n<p>Despu&eacute;s de dos d&iacute;as seguidos de perder la batalla contra los niveles elevados de glucosa en sangre , decid&iacute; ceder y cambiar el sitio de infusi&oacute;n de mi bomba. Ni siquiera estoy seguro de por qu&eacute; esper&eacute; tanto para hacerlo, adem&aacute;s del orgullo y la estupidez. Mi glucosa ya estaba cerca del rango de los 300. &nbsp;Y luego subi&oacute; m&aacute;s all&aacute; y ya no pude controlarlo. &nbsp;Estaba agotado f&iacute;sica y emocionalmente, mentalmente exhausto, y no hab&iacute;a visto que la CAD estaba acechando a la vuelta de la esquina como algo salido de una pel&iacute;cula de &laquo;El Se&ntilde;or de los Anillos&raquo;.<\/p>\n<p>La sensaci&oacute;n de dolor en mis brazos y piernas, el sabor en mi boca, la deshidrataci&oacute;n, todo lleg&oacute; a un punto cr&iacute;tico y le dije a mi esposa Gina que pensaba deb&iacute;amos ir al hospital &hellip; Estoy en CAD. Ella no dud&oacute;, solo tom&oacute; nuestras cosas y nos dirigimos al hospital. &iexcl;Casi no parec&iacute;a una emergencia y no quer&iacute;a molestar a nadie porque era tan vergonzoso! Soy un miembro portador de la tarjeta de la comunidad de diabetes tipo 1, &iexcl;por amor el de Dios! A mi no puede darme CAD, &iexcl;simplemente no sucede as&iacute;! &iexcl;No en mi caso!<\/p>\n<\/div>\n<div class=\"column\">\n<p>Me ingresaron en la sala de emergencias, les expliqu&eacute; lo que estaba sucediendo y, de inmediato, los m&eacute;dicos de la sala de emergencias dijeron: &laquo;Tiene raz&oacute;n, est&aacute; en CAD&raquo; y me admitieron en el hospital. Rid&iacute;culo, &iexcl;&iquest;verdad ?! Mir&eacute; hacia un punto en la sala de emergencias y vi que llevaba una camiseta de Beyond Type 1 y trat&eacute; de explicarle al m&eacute;dico que solo necesitaba una inyecci&oacute;n intravenosa con algunos l&iacute;quidos y estar&iacute;a bien. Despu&eacute;s de todo, llevaba mi camisa de BT1 &hellip; Estoy por encima de la ley, &iquest;verdad?<\/p>\n<p>El equipo me administr&oacute; un goteo intravenoso con una gran cantidad de potasio, vitaminas y electrolitos y luego me inform&oacute; que pasar&iacute;a la noche en el hospital, posiblemente m&aacute;s tiempo mientras monitoreaban algo llamado &laquo;brecha ani&oacute;nica&raquo; y el equilibrio del pH en mi sangre. &iexcl;Qu&eacute; atrevimiento! Mi orgullo estaba en su punto m&aacute;s alto y solo quer&iacute;a irme a casa, a pesar de que la cantidad de dolor en el que estaba era de alrededor de 8+.<\/p>\n<\/div>\n<div class=\"column\">\n<p>El m&eacute;dico me pregunt&oacute; c&oacute;mo hab&iacute;a permitido que mi glucosa se saliera de control y le dije que normalmente ten&iacute;a un gran control, pero mi sitio de infusi&oacute;n se deterior&oacute; y me puse terco. Y luego dijo algo que me enfureci&oacute;: &laquo;Todo ese buen control realmente no te ayud&oacute; hoy, &iquest;verdad?&raquo;<\/p>\n<p>Quer&iacute;a pararme, arrancarme la aguja IV de mi brazo y decir (con voz de Victor Garber), &raquo; &iquest;Tienes alguna idea de qui&eacute;n soy? Hice un <a href=\"https:\/\/beyondtype1.org\/es\/bike-beyond-the-documentary-screening-camp-ho-mita-koda\/\">maldito documental sobre ciclistas con diabetes tipo 1<\/a>, &iexcl;por el amor de Dios, hombre! &laquo;Pero no dije una palabra. Me tragu&eacute; mi orgullo y asent&iacute;. Tuve perspectiva de algo por primera vez en 27 a&ntilde;os de vivir con esta enfermedad.<\/p>\n<h2>Una nueva toma<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Por alguna raz&oacute;n, hasta que me encontr&eacute; en esa situaci&oacute;n, cuando ve&iacute;a una foto de alguien en el hospital con CAD o niveles fuera de control &hellip; no me daba cuenta. Pero ahora se que una parte de m&iacute; los estaba juzgando. Casi como si dijera &laquo;Bueno, si solo trabajaran m&aacute;s duro&raquo; o &laquo;Apuesto a que se comieron todos los Cake Rolls suizos&raquo;. Y cuando me qued&eacute; en el hospital dos d&iacute;as consecutivos recuper&aacute;ndome, me di cuenta de que la CAD no respeta a nadie. No es algo a lo que sea inmune o incapaz de ser presa. No fue la CAD la que me golpe&oacute; ese d&iacute;a en el hospital, fue una buena dosis de humildad y comprensi&oacute;n.<\/p>\n<\/div>\n<div class=\"column\">\n<p>He ayudado a Beyond Type 1 a distribuir publicaciones y presentaciones educativas sobre CAD en los &uacute;ltimos a&ntilde;os. Pero ese d&iacute;a en el hospital, apreci&eacute; m&aacute;s a las personas a las que golpea y sent&iacute; menos miedo a los s&iacute;ntomas de la CAD. S&iacute;, es mortal. S&iacute;, es un monstruo. S&iacute;, es una situaci&oacute;n poco comprendida. Pero las personas a las que afecta, pueden ser t&uacute; o yo. Buen control o mal control, no me tiene m&aacute;s respeto simplemente porque soy voluntario y hago <a href=\"https:\/\/www.instagram.com\/p\/Br_3NkvAcik\" target=\"_blank\" rel=\"noopener noreferrer\">videos en Instagram<\/a> sobre la diabetes, a la CAD no le importa. Y necesitaba comenzar a preocuparme m&aacute;s por cualquiera y por todos los que est&aacute;n sentados en un hospital con una IV en ellos, sintiendo que le palpitan los brazos, el mal sabor de boca y deseando no estar all&iacute;.<\/p>\n<p>La pr&oacute;xima vez que veas una imagen en las redes sociales de alguien que se encuentre en ese lugar en el que hemos estado muchos de nosotros, te desaf&iacute;o a que aprendas de mis errores y que tengas compasi&oacute;n, que ayudes a alentarlos, que hagas lo que sea necesario para apoyarlos. Porque tienen un nombre y CAD son solo 3 letras rid&iacute;culas que no deber&iacute;an tener ning&uacute;n poder sobre nosotros.<\/p>\n<hr>\n<p>Este art&iacute;culo forma parte de los recursos de Beyond Type 1 sobre el manejo de cetonas: encuentra la colecci&oacute;n completa de recursos <a href=\"https:\/\/beyondtype1.org\/es\/todo-sobre-cetonas-y-cad\/\">aqu&iacute;<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Historia Real No me siento como un idiota, ni un inepto, ni estoy completamente loco &hellip; pero as&iacute; es como imaginaba que la gente me tratar&iacute;a cuando entr&eacute; en cetoacidosis diab&eacute;tica (CAD) no hace mucho. En los 27 a&ntilde;os que he vivido con diabetes tipo 1 &nbsp;no hay letras m&aacute;s aterradoras que la temida C-A-D. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12991,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12989","resources","type-resources","status-publish","has-post-thumbnail","hentry","diabetes-types-tipo-1","tags-dka_story"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;Esto no me pasa a mi&#039;: una nueva perspectiva sobre CAD | Beyond Type 1<\/title>\n<meta name=\"description\" content=\"Neil Greathouse comparte su experiencia con DKA y c\u00f3mo el incidente realmente lo hizo m\u00e1s humilde. De nuestra serie de CAD.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Esto no me pasa a mi&#039;: una nueva perspectiva sobre CAD | Beyond Type 1\" \/>\n<meta property=\"og:description\" content=\"Neil Greathouse comparte su experiencia con DKA y c\u00f3mo el incidente realmente lo hizo m\u00e1s humilde. De nuestra serie de CAD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Type 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beyondtype1\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/neilheader.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeyondType1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/\",\"name\":\"'Esto no me pasa a mi': una nueva perspectiva sobre CAD | Beyond Type 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/neilheader.png\",\"datePublished\":\"2019-06-19T20:28:30+00:00\",\"description\":\"Neil Greathouse comparte su experiencia con DKA y c\u00f3mo el incidente realmente lo hizo m\u00e1s humilde. De nuestra serie de CAD.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/neilheader.png\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/neilheader.png\",\"width\":2048,\"height\":733},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8216;Esto no me pasa a mi&#8217;: una nueva perspectiva sobre CAD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"name\":\"Beyond Type 1\",\"description\":\"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\",\"name\":\"Beyond Type 1\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"width\":56,\"height\":56,\"caption\":\"Beyond Type 1\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beyondtype1\",\"https:\\\/\\\/x.com\\\/BeyondType1\",\"http:\\\/\\\/instagram.com\\\/BeyondType1\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/BeyondType1\",\"https:\\\/\\\/www.tiktok.com\\\/@beyondtype1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beyond-type1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Esto no me pasa a mi': una nueva perspectiva sobre CAD | Beyond Type 1","description":"Neil Greathouse comparte su experiencia con DKA y c\u00f3mo el incidente realmente lo hizo m\u00e1s humilde. De nuestra serie de CAD.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/","og_locale":"es_ES","og_type":"article","og_title":"'Esto no me pasa a mi': una nueva perspectiva sobre CAD | Beyond Type 1","og_description":"Neil Greathouse comparte su experiencia con DKA y c\u00f3mo el incidente realmente lo hizo m\u00e1s humilde. De nuestra serie de CAD.","og_url":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/","og_site_name":"Beyond Type 1","article_publisher":"https:\/\/www.facebook.com\/beyondtype1","og_image":[{"width":2048,"height":733,"url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/neilheader.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BeyondType1","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/","url":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/","name":"'Esto no me pasa a mi': una nueva perspectiva sobre CAD | Beyond Type 1","isPartOf":{"@id":"https:\/\/beyondtype1.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/#primaryimage"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/#primaryimage"},"thumbnailUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/neilheader.png","datePublished":"2019-06-19T20:28:30+00:00","description":"Neil Greathouse comparte su experiencia con DKA y c\u00f3mo el incidente realmente lo hizo m\u00e1s humilde. De nuestra serie de CAD.","breadcrumb":{"@id":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/#primaryimage","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/neilheader.png","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/neilheader.png","width":2048,"height":733},{"@type":"BreadcrumbList","@id":"https:\/\/beyondtype1.org\/es\/esto-no-me-pasa-a-mi-una-nueva-perspectiva-sobre-cad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondtype1.org\/es\/"},{"@type":"ListItem","position":2,"name":"&#8216;Esto no me pasa a mi&#8217;: una nueva perspectiva sobre CAD"}]},{"@type":"WebSite","@id":"https:\/\/beyondtype1.org\/es\/#website","url":"https:\/\/beyondtype1.org\/es\/","name":"Beyond Type 1","description":"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.","publisher":{"@id":"https:\/\/beyondtype1.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondtype1.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/beyondtype1.org\/es\/#organization","name":"Beyond Type 1","url":"https:\/\/beyondtype1.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","width":56,"height":56,"caption":"Beyond Type 1"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondtype1","https:\/\/x.com\/BeyondType1","http:\/\/instagram.com\/BeyondType1\/","https:\/\/www.youtube.com\/c\/BeyondType1","https:\/\/www.tiktok.com\/@beyondtype1","https:\/\/www.linkedin.com\/company\/beyond-type1\/"]}]}},"_links":{"self":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/12989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/comments?post=12989"}],"version-history":[{"count":0,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/12989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media\/12991"}],"wp:attachment":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media?parent=12989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}