{"id":17662,"date":"2022-05-05T23:31:12","date_gmt":"2022-05-05T23:31:12","guid":{"rendered":"https:\/\/beyondtype2.org\/resources\/estudio-perdida-de-peso-medicamento-tirzepatida\/"},"modified":"2022-05-05T23:31:12","modified_gmt":"2022-05-05T23:31:12","slug":"estudio-perdida-de-peso-medicamento-tirzepatida","status":"publish","type":"resources","link":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/","title":{"rendered":"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El <\/span><a href=\"https:\/\/www.prnewswire.com\/news-releases\/lillys-tirzepatide-delivered-up-to-22-5-weight-loss-in-adults-with-obesity-or-overweight-in-surmount-1--301534871.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">&uacute;ltimo estudio<\/span><\/a><span style=\"font-weight: 400;\"> sobre un nuevo medicamento que tiene como objetivo tratar la diabetes o la obesidad est&aacute; en los titulares por su impresionante capacidad para ayudar a quienes tienen dificultades para perder peso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La tirzepatida es un medicamento inyectable una vez por semana de Lilly Diabetes. Ser&aacute; el primer y &uacute;nico agonista doble del receptor GIP\/GLP-1 una vez aprobado por la Administraci&oacute;n de Alimentos y Medicamentos de los Estados Unidos (FDA, por sus siglas en ingl&eacute;s) probablemente en la segunda mitad de 2022.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si bien los <\/span><a href=\"https:\/\/beyondtype1.org\/medications-type-2-diabetes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">medicamentos<\/span><\/a><span style=\"font-weight: 400;\"> como la tirzepatida generalmente se consideran un tratamiento para la diabetes tipo 2, otras clases de medicamentos relacionados a veces se recetan como de &ldquo;uso no previsto&rdquo; a personas con diabetes tipo 1 que luchan contra la obesidad o el sobrepeso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El estudio SURMOUNT-1 m&aacute;s reciente consisti&oacute; en 2,539 participantes con un peso corporal inicial promedio de 231 libras.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Con la dosis m&aacute;s baja, 5 mg, los participantes perdieron el 15 % de su peso corporal en un plazo de 72 semanas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En dosis m&aacute;s altas (10 y 15 mg), los participantes perdieron alrededor del 20 % de su peso corporal durante 72 semanas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">M&aacute;s de la mitad de los participantes que se administraron la dosis m&aacute;s alta perdieron el 20 % de su peso corporal en comparaci&oacute;n con solo el 1.3 % que se administr&oacute; un placebo.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En el mejor de los casos, muchos participantes perdieron el 22.5 % de su peso corporal, alrededor de 52 libras de un peso inicial de 231 libras.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">&ldquo;La tirzepatida es el primer medicamento en investigaci&oacute;n que ofrece una p&eacute;rdida de peso de m&aacute;s del 20 por ciento en promedio en un estudio de fase 3, lo que refuerza nuestra confianza en su potencial para ayudar a las personas que viven con obesidad&rdquo;, dijo Jeff Emmick, doctor en medicina, Ph.D., vicepresidente, desarrollo de productos, Lilly.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&ldquo;La obesidad es una enfermedad cr&oacute;nica que requiere opciones de tratamiento efectivas, y Lilly est&aacute; trabajando sin descanso para apoyar a las personas con obesidad y modernizar la forma en que se aborda esta enfermedad&rdquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero la tirzepatida tiene m&aacute;s que la p&eacute;rdida de peso para ofrecer a las personas con cualquier tipo de diabetes. Echemos un vistazo a c&oacute;mo funciona y los beneficios demostrados por medio de otros estudios recientes.<\/span><\/p>\n<h3><b><i>&iquest;C&Oacute;MO FUNCIONA LA TIRZEPATIDA?<\/i><\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A pesar de las docenas de <\/span><a href=\"https:\/\/beyondtype1.org\/medications-type-2-diabetes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">medicamentos para la diabetes<\/span><\/a><span style=\"font-weight: 400;\"> que ya existen, la tirzepatida ofrece algo que ning&uacute;n otro ofrece. Combina dos componentes por primera vez para brindar una poderosa variedad de beneficios. Estos dos componentes son:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">polip&eacute;ptido insulinotr&oacute;pico dependiente de glucosa (GIP, por sus siglas en ingl&eacute;s)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">p&eacute;ptido similar al glucag&oacute;n-1 (GLP-1, por sus siglas en ingl&eacute;s)<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Trabajando juntos, este doble GIP\/GLP-1 puede tener los siguientes efectos en la salud de tu diabetes:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">aumentar tu producci&oacute;n natural de insulina (diabetes tipo 2)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">mejorar tu sensibilidad a la insulina<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">reducir la cantidad de glucosa (az&uacute;car) que produce tu h&iacute;gado<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">retrasar el proceso de digesti&oacute;n<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Si bien estos beneficios pueden parecer simples, tienen el potencial de cambiar por completo la forma en que tu cuerpo maneja la glucosa (az&uacute;car) y la insulina.<\/span><\/p>\n<h3><b><i>ESTUDIOS ANTERIORES SOBRE LA TIRZEPATIDA<\/i><\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Antes del estudio SURMOUNT-1, hubo una variedad de <\/span><a href=\"https:\/\/medcitynews.com\/2021\/05\/eli-lilly-looks-ahead-to-fda-after-diabetes-drug-wraps-up-last-clinical-test\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">estudios notables<\/span><\/a><span style=\"font-weight: 400;\"> sobre la tirzepatida: <\/span><a href=\"https:\/\/clinicaltrials.gov\/ct2\/show\/NCT03882970\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">SURPASS-3<\/span><\/a><span style=\"font-weight: 400;\">, <\/span><a href=\"https:\/\/clinicaltrials.gov\/ct2\/show\/NCT04039503\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">SURPASS-5<\/span><\/a><span style=\"font-weight: 400;\"> y <\/span><a href=\"https:\/\/clinicaltrials.gov\/ct2\/show\/NCT03987919\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">SURPASS-2<\/span><\/a><span style=\"font-weight: 400;\">. La fase tres m&aacute;s reciente de <\/span><a href=\"https:\/\/www.healio.com\/news\/endocrinology\/20210520\/surpass4-tirzepatide-reduces-hba1c-body-weight-in-type-2-diabetes\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">SURPASS-4<\/span><\/a><span style=\"font-weight: 400;\"> incluy&oacute; a m&aacute;s de <\/span><a href=\"https:\/\/medcitynews.com\/2021\/05\/eli-lilly-looks-ahead-to-fda-after-diabetes-drug-wraps-up-last-clinical-test\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">13,000 participantes<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Reducci&oacute;n de A1c: <\/b><span style=\"font-weight: 400;\">Los participantes del ensayo con niveles de A1c a partir del 8.0 % experimentaron una reducci&oacute;n de aproximadamente 2.5 puntos. Por ejemplo: del 9.5 % hasta un 7.0 %. Seg&uacute;n los informes de SURPASS-4, el 91 % de los participantes logr&oacute; un A1c del 7 % o menos, mientras que el 43 % logr&oacute; un A1c del 5.7 % o menos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>P&eacute;rdida de peso:<\/b><span style=\"font-weight: 400;\"> La p&eacute;rdida de peso m&aacute;s significativa en comparaci&oacute;n con cualquier otro medicamento para la diabetes. La p&eacute;rdida de peso promedio despu&eacute;s de 52 semanas fue de alrededor de 25 libras. Los participantes del ensayo que se administraron la dosis m&aacute;s alta (15 mg) perdieron alrededor de 27 libras, y con la dosis m&aacute;s baja (5 mg) alrededor de 17 libras.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Menor riesgo de hipoglucemia en comparaci&oacute;n con otros medicamentos:<\/b><span style=\"font-weight: 400;\"> S&iacute;, la tirzepatida puede causar niveles bajos de glucosa (az&uacute;car) en sangre, pero el riesgo parece ser <\/span><a href=\"https:\/\/www.healio.com\/news\/endocrinology\/20210629\/surpass-data-impressive-tirzepatide-could-change-goals-for-diabetes-treatment\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">m&iacute;nimo<\/span><\/a><span style=\"font-weight: 400;\"> en comparaci&oacute;n con la administraci&oacute;n de insulina o una sulfonilurea. Cuando empieces a administrarte tirzepatida, trabajar&aacute;s en estrecha colaboraci&oacute;n con tu m&eacute;dico para ajustar otros medicamentos para la diabetes, incluyendo la insulina, seg&uacute;n sea necesario.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Reducci&oacute;n de triglic&eacute;ridos y colesterol:<\/b><span style=\"font-weight: 400;\"> despu&eacute;s de 52 semanas, la dosis m&aacute;s alta de tirzepatida redujo el colesterol total en aproximadamente un 5.6 %, los triglic&eacute;ridos en un 22.5 %, el colesterol LDL (lipoprote&iacute;nas de baja densidad, por sus siglas en ingl&eacute;s) en un 7.9 %, las VLDL (lipoprote&iacute;na de muy baja densidad, por sus siglas en ingl&eacute;s) en un 21.8 % y aument&oacute; el HDL (lipoprote&iacute;na de alta densidad, por sus siglas en ingl&eacute;s) en un 10.8 %.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Los estudios sobre la tirzepatida contin&uacute;an evaluando los beneficios potenciales que tiene para quienes luchan contra la obesidad, la diabetes tipo 2 y la prediabetes. Se esperan m&aacute;s resultados del estudio SURMOUNT m&aacute;s reciente en 2023.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&nbsp;<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Este contenido menciona a Lilly, un socio activo de Beyond Type 1.<\/span><\/i><\/p>\n<p><i><span style=\"font-weight: 400;\">La cobertura de noticias del equipo de Beyond Type 1 se hace independientemente de cualquier asociaci&oacute;n de contenido. Beyond Type 1 mantiene un control editorial completo de todo el contenido publicado en nuestras plataformas.<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>El &uacute;ltimo estudio sobre un nuevo medicamento que tiene como objetivo tratar la diabetes o la obesidad est&aacute; en los titulares por su impresionante capacidad para ayudar a quienes tienen dificultades para perder peso. La tirzepatida es un medicamento inyectable una vez por semana de Lilly Diabetes. Ser&aacute; el primer y &uacute;nico agonista doble del [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17664,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-17662","resources","type-resources","status-publish","has-post-thumbnail","hentry","diabetes-types-tipo-1","tags-new_home_latest","tags-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad | Beyond Type 1<\/title>\n<meta name=\"description\" content=\"El \u00faltimo estudio sobre un nuevo f\u00e1rmaco para la diabetes tipo 2 es noticia por su impresionante capacidad para ayudar a la p\u00e9rdida de peso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad | Beyond Type 1\" \/>\n<meta property=\"og:description\" content=\"El \u00faltimo estudio sobre un nuevo f\u00e1rmaco para la diabetes tipo 2 es noticia por su impresionante capacidad para ayudar a la p\u00e9rdida de peso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Type 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beyondtype1\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeyondType1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/\",\"name\":\"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad | Beyond Type 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg\",\"datePublished\":\"2022-05-05T23:31:12+00:00\",\"description\":\"El \u00faltimo estudio sobre un nuevo f\u00e1rmaco para la diabetes tipo 2 es noticia por su impresionante capacidad para ayudar a la p\u00e9rdida de peso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg\",\"width\":1200,\"height\":429},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/estudio-perdida-de-peso-medicamento-tirzepatida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"name\":\"Beyond Type 1\",\"description\":\"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\",\"name\":\"Beyond Type 1\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"width\":56,\"height\":56,\"caption\":\"Beyond Type 1\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beyondtype1\",\"https:\\\/\\\/x.com\\\/BeyondType1\",\"http:\\\/\\\/instagram.com\\\/BeyondType1\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/BeyondType1\",\"https:\\\/\\\/www.tiktok.com\\\/@beyondtype1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beyond-type1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad | Beyond Type 1","description":"El \u00faltimo estudio sobre un nuevo f\u00e1rmaco para la diabetes tipo 2 es noticia por su impresionante capacidad para ayudar a la p\u00e9rdida de peso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/","og_locale":"es_ES","og_type":"article","og_title":"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad | Beyond Type 1","og_description":"El \u00faltimo estudio sobre un nuevo f\u00e1rmaco para la diabetes tipo 2 es noticia por su impresionante capacidad para ayudar a la p\u00e9rdida de peso.","og_url":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/","og_site_name":"Beyond Type 1","article_publisher":"https:\/\/www.facebook.com\/beyondtype1","og_image":[{"width":1200,"height":429,"url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BeyondType1","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/","url":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/","name":"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad | Beyond Type 1","isPartOf":{"@id":"https:\/\/beyondtype1.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/#primaryimage"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/#primaryimage"},"thumbnailUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg","datePublished":"2022-05-05T23:31:12+00:00","description":"El \u00faltimo estudio sobre un nuevo f\u00e1rmaco para la diabetes tipo 2 es noticia por su impresionante capacidad para ayudar a la p\u00e9rdida de peso.","breadcrumb":{"@id":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/#primaryimage","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT2-ES-RESEARCH-UPDATE-TIRZEPATIDE-LEAD-22.5-WEIGHT-LOSS-IN-ADULTS-HEADER-1200x429-1.jpg","width":1200,"height":429},{"@type":"BreadcrumbList","@id":"https:\/\/beyondtype1.org\/es\/estudio-perdida-de-peso-medicamento-tirzepatida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondtype1.org\/es\/"},{"@type":"ListItem","position":2,"name":"Un nuevo medicamento prometedor lleva a una p\u00e9rdida de peso de 22,5% en adultos con obesidad"}]},{"@type":"WebSite","@id":"https:\/\/beyondtype1.org\/es\/#website","url":"https:\/\/beyondtype1.org\/es\/","name":"Beyond Type 1","description":"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.","publisher":{"@id":"https:\/\/beyondtype1.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondtype1.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/beyondtype1.org\/es\/#organization","name":"Beyond Type 1","url":"https:\/\/beyondtype1.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","width":56,"height":56,"caption":"Beyond Type 1"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondtype1","https:\/\/x.com\/BeyondType1","http:\/\/instagram.com\/BeyondType1\/","https:\/\/www.youtube.com\/c\/BeyondType1","https:\/\/www.tiktok.com\/@beyondtype1","https:\/\/www.linkedin.com\/company\/beyond-type1\/"]}]}},"_links":{"self":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/17662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/comments?post=17662"}],"version-history":[{"count":0,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/17662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media\/17664"}],"wp:attachment":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media?parent=17662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}