{"id":22746,"date":"2018-04-23T15:00:41","date_gmt":"2018-04-23T15:00:41","guid":{"rendered":"https:\/\/beyondtype2.org\/resources\/la-ley-impuesta-por-intimidacion\/"},"modified":"2018-04-23T15:00:41","modified_gmt":"2018-04-23T15:00:41","slug":"la-ley-impuesta-por-intimidacion","status":"publish","type":"resources","link":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/","title":{"rendered":"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Al comprar medicamentos recetados en los EE. UU., tu seguro quiz&aacute;s no sea la opci&oacute;n m&aacute;s econ&oacute;mica. A veces, los medicamentos comprados en efectivo son de hecho m&aacute;s baratos y no hay forma de saberlo. La ley mordaza que a&uacute;n existe en la mayor&iacute;a de los estados impide que los farmac&eacute;uticos le digan a los clientes que una opci&oacute;n en efectivo es la mejor. Por ejemplo, un consumidor da un copago de $100 con su plan de seguro por un medicamento hubiera pagado&nbsp;$ 70 si hubiera pagado en efectivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta diferencia de precio o &laquo;reembolso&raquo; corresponde al administrador de beneficios de farmacia (PBM, por sus siglas en ingl&eacute;s) que es el intermediario para negociar los precios de los medicamentos entre la farmacia y el distribuidor farmac&eacute;utico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La fijaci&oacute;n de precios de medicamentos con receta en los Estados Unidos es un problema de m&uacute;ltiples capas que involucra a estos tres jugadores, y la parte que los PBM juegan generalmente ocurre detr&aacute;s de bambalinas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seg&uacute;n un <\/span><a href=\"https:\/\/www.whitehouse.gov\/wp-content\/uploads\/2017\/11\/CEA-Rx-White-Paper-Final2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><b>informe<\/b><\/a><span style=\"font-weight: 400;\"> reciente del Consejo de Asesores Econ&oacute;micos de la Casa Blanca, &laquo;El mercado de los PBM est&aacute; altamente concentrado. Tres PBM representan el 85%&nbsp; del mercado, lo que les permite ejercer un poder indebido en el mercado contra los fabricantes y contra los planes de salud y los beneficiarios que supuestamente representan, generandoenormes ganancias para ellos&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Antonio Ciaccia, Director de Asuntos P&uacute;blicos y del Gobierno de la Asociaci&oacute;n de Farmac&eacute;uticos de Ohio, dijo: &laquo;Esta es la garant&iacute;a que les da la fortaleza que estas tres empresas tienen sobre el mercado&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Desde la fusi&oacute;n en 2015 de United Health, OptumRx y Catamaran, esta compa&ntilde;&iacute;a junto con Express Scripts, CVS Health (anteriormente CVS Caremark) forman parte de las tres m&aacute;s importantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta pr&aacute;ctica es t&eacute;cnicamente legal, aunque bajo el derecho contractual b&aacute;sico. &laquo;Los PBM tienen un lenguaje en un contrato sobre lo espec&iacute;fico que puede decir un farmac&eacute;utico&raquo;, dijo Ciaccia. &laquo;Se les dice que no le digan nada al paciente que pueda considerarse patentado&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque todav&iacute;a es legal en algunos estados, la falta de transparencia en los precios no es &eacute;tica e inhibe un mercado de comercio libre , por no mencionar el alto costo para el consumidor. Adem&aacute;s, las compa&ntilde;&iacute;as que lo est&aacute;n perpetuando son conscientes de que la conducta no tiene escr&uacute;pulos por el m&eacute;todo en el que &laquo;alientan&raquo; a los farmac&eacute;uticos a no romper la ley mordaza.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Antonio Ciaccia describi&oacute; un incidente en el que una farmacia en Columbus, Ohio, le dijo al paciente que se le cobraba m&aacute;s que el precio en efectivo del medicamento al usar su seguro y el paciente present&oacute; una queja a la compa&ntilde;&iacute;a de seguros. Poco despu&eacute;s, Ciaccia dijo que la farmacia recibi&oacute; una advertencia de que su contrato se cancelar&iacute;a si continuaban divulgando la informaci&oacute;n de precios a los clientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando se le pregunt&oacute; lo que dec&iacute;an las cartas de advertencia, Ciaccia dijo: &laquo;Raramente esas solicitudes se producen por correo postal. Por lo general, se trata de una llamada telef&oacute;nica. Los rastros de papel son poco comunes&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ciaccia dijo que s&iacute; sab&iacute;a de un par de farmacias que estaban divulgando algunas pr&aacute;cticas de los PBM a los empleadores, y los PMB volvieron y cancelaron sus contratos. Atribuido a este hecho o no, se fueron a la quiebra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&laquo;Generalmente, cuando la farmacia recibe una advertencia, cambia la forma en que hace negocios&raquo;, dijo Ciaccia. &laquo;Es imponer una ley por medio de la intimidaci&oacute;n&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, la gente est&aacute; hablando y haci&eacute;ndoles frente a los poderosos PBM, y los que denuncian generalmente son los farmac&eacute;uticos. Arriesgando de su sustento, est&aacute;n buscando legisladores para decirles que hay un problema.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una forma de cambiar esta pr&aacute;ctica es la legislaci&oacute;n estado por estado, ya que cada estado tiene un organismo regulador para determinar c&oacute;mo las compa&ntilde;&iacute;as de seguros llevan a cabo sus negocios, y aprobar todo de forma federal generalmente lleva m&aacute;s tiempo. Al menos 15 estados ya han tenido &eacute;xito en descartar la ley mordaza con reembolso e incluyen: Maryland, Arkansas, Louisiana, Maine, Kansas, Connecticut, Carolina del Norte, Dakota del Sur y del Norte, Georgia, Minnesota, Virginia, Mississippi, Texas, y m&aacute;s recientemente, Ohio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&laquo;El objetivo del seguro es ahorrar dinero a los consumidores&raquo;, dijo la Senadora <\/span><a href=\"http:\/\/thehill.com\/people\/susan-collins\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Susan Collins<\/b><\/a><span style=\"font-weight: 400;\"> (R-Maine). &laquo;Las cl&aacute;usulas mordaza en los contratos que proh&iacute;ben a los farmac&eacute;uticos informar a los pacientes sobre mejores precios de medicamentos recetados hacen lo contrario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&laquo;Los estadounidenses tienen derecho a saber qu&eacute; m&eacute;todo de pago (con seguro o en efectivo) proporcionar&iacute;a la mayor cantidad de ahorro al comprar medicamentos recetados&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunos argumentan que los clientes que pagan m&aacute;s que el precio del mercado de los medicamentos son poco comunes; sin embargo, una <\/span><a href=\"https:\/\/jamanetwork.com\/journals\/jama\/article-abstract\/2674655?redirect=true\" target=\"_blank\" rel=\"noopener noreferrer\"><b>encuesta de 2016<\/b><\/a><span style=\"font-weight: 400;\"> de farmac&eacute;uticos independientes revel&oacute; que de 9.5 millones de reclamaciones en los EE. UU., 2.2 millones involucraron pagos en exceso. Seg&uacute;n esta encuesta, los clientes pagan en exceso por los medicamentos recetados casi una cuarta parte del tiempo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Peor a&uacute;n, 12 de los 20 medicamentos m&aacute;s recetados ten&iacute;an tasas de sobrepago superiores al 33 por ciento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque el sobrepago promedio por miembro fue de $ 10.51, un PBM grande inform&oacute; que el popular medicamento para la diabetes tipo 2, la metformina, era de $ 10.67 por miembro.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Asociaci&oacute;n Nacional de Farmac&eacute;uticos Comunitarios (NCPA, por sus siglas en ingl&eacute;s) encontr&oacute; en otra <\/span><a href=\"http:\/\/www.ncpanet.org\/newsroom\/news-releases\/2016\/06\/28\/pharmacists-survey-prescription-drug-costs-skewed-by-fees-on-pharmacies-patients\" target=\"_blank\" rel=\"noopener noreferrer\"><b>encuesta<\/b><\/a><span style=\"font-weight: 400;\"> de 640 farmac&eacute;uticos que &laquo;los planes de medicamentos de Aetna y CVS Caremark son los m&aacute;s atroces en esta &aacute;rea [de reembolsos]&raquo;. La controvertida fusi&oacute;n de estas dos compa&ntilde;&iacute;as fue aprobada por el Congreso el a&ntilde;o pasado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&laquo;Los PBM tienen sus tent&aacute;culos en todo&raquo;, dijo Ciaccia. &laquo;Est&aacute;n exigiendo descuentos de las compa&ntilde;&iacute;as farmac&eacute;uticas. Las compa&ntilde;&iacute;as farmac&eacute;uticas elevan sus precios para compensar esos descuentos y los precios de los medicamentos contin&uacute;an aumentando&raquo;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&laquo;En caso de duda, pregunten por el precio en efectivo&raquo;, aconsej&oacute; Ciaccia. &laquo;Si el paciente inicia la conversaci&oacute;n, el farmac&eacute;utico no es visto como el &lsquo;creador de problemas&rsquo; a los ojos del PMB.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pregunten: &lsquo;&iquest;Ser&iacute;a esto m&aacute;s barato si pagara en efectivo?'&raquo;<\/span><\/p>\n<hr>\n<p><a href=\"http:\/\/esbeyondtype1.wpengine.com\/acceso\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Lea m&aacute;s sobre la acceso global.<\/b><\/a><\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Al comprar medicamentos recetados en los EE. UU., tu seguro quiz&aacute;s no sea la opci&oacute;n m&aacute;s econ&oacute;mica. A veces, los medicamentos comprados en efectivo son de hecho m&aacute;s baratos y no hay forma de saberlo. La ley mordaza que a&uacute;n existe en la mayor&iacute;a de los estados impide que los farmac&eacute;uticos le digan a los [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":22748,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-22746","resources","type-resources","status-publish","has-post-thumbnail","hentry","diabetes-types-tipo-1","tags-noticias","tags-usanews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS | Beyond Type 1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS | Beyond Type 1\" \/>\n<meta property=\"og:description\" content=\"Al comprar medicamentos recetados en los EE. UU., tu seguro quiz&aacute;s no sea la opci&oacute;n m&aacute;s econ&oacute;mica. A veces, los medicamentos comprados en efectivo son de hecho m&aacute;s baratos y no hay forma de saberlo. La ley mordaza que a&uacute;n existe en la mayor&iacute;a de los estados impide que los farmac&eacute;uticos le digan a los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Type 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beyondtype1\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HEADER-ESPANOL-GAG-RULE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeyondType1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/\",\"name\":\"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS | Beyond Type 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT1-HEADER-ESPANOL-GAG-RULE.png\",\"datePublished\":\"2018-04-23T15:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT1-HEADER-ESPANOL-GAG-RULE.png\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT1-HEADER-ESPANOL-GAG-RULE.png\",\"width\":2048,\"height\":733},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/la-ley-impuesta-por-intimidacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"name\":\"Beyond Type 1\",\"description\":\"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\",\"name\":\"Beyond Type 1\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"width\":56,\"height\":56,\"caption\":\"Beyond Type 1\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beyondtype1\",\"https:\\\/\\\/x.com\\\/BeyondType1\",\"http:\\\/\\\/instagram.com\\\/BeyondType1\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/BeyondType1\",\"https:\\\/\\\/www.tiktok.com\\\/@beyondtype1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beyond-type1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS | Beyond Type 1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/","og_locale":"es_ES","og_type":"article","og_title":"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS | Beyond Type 1","og_description":"Al comprar medicamentos recetados en los EE. UU., tu seguro quiz&aacute;s no sea la opci&oacute;n m&aacute;s econ&oacute;mica. A veces, los medicamentos comprados en efectivo son de hecho m&aacute;s baratos y no hay forma de saberlo. La ley mordaza que a&uacute;n existe en la mayor&iacute;a de los estados impide que los farmac&eacute;uticos le digan a los [&hellip;]","og_url":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/","og_site_name":"Beyond Type 1","article_publisher":"https:\/\/www.facebook.com\/beyondtype1","og_image":[{"width":2048,"height":733,"url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HEADER-ESPANOL-GAG-RULE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BeyondType1","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/","url":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/","name":"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS | Beyond Type 1","isPartOf":{"@id":"https:\/\/beyondtype1.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/#primaryimage"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/#primaryimage"},"thumbnailUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HEADER-ESPANOL-GAG-RULE.png","datePublished":"2018-04-23T15:00:41+00:00","breadcrumb":{"@id":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/#primaryimage","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HEADER-ESPANOL-GAG-RULE.png","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HEADER-ESPANOL-GAG-RULE.png","width":2048,"height":733},{"@type":"BreadcrumbList","@id":"https:\/\/beyondtype1.org\/es\/la-ley-impuesta-por-intimidacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondtype1.org\/es\/"},{"@type":"ListItem","position":2,"name":"LA LEY IMPUESTA POR INTIMIDACI\u00d3N: EL CONTRATO QUE MANTIENE CALLADOS A LOS FARMAC\u00c9UTICOS"}]},{"@type":"WebSite","@id":"https:\/\/beyondtype1.org\/es\/#website","url":"https:\/\/beyondtype1.org\/es\/","name":"Beyond Type 1","description":"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.","publisher":{"@id":"https:\/\/beyondtype1.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondtype1.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/beyondtype1.org\/es\/#organization","name":"Beyond Type 1","url":"https:\/\/beyondtype1.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","width":56,"height":56,"caption":"Beyond Type 1"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondtype1","https:\/\/x.com\/BeyondType1","http:\/\/instagram.com\/BeyondType1\/","https:\/\/www.youtube.com\/c\/BeyondType1","https:\/\/www.tiktok.com\/@beyondtype1","https:\/\/www.linkedin.com\/company\/beyond-type1\/"]}]}},"_links":{"self":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/22746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/comments?post=22746"}],"version-history":[{"count":0,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/22746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media\/22748"}],"wp:attachment":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media?parent=22746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}