{"id":31860,"date":"2021-12-22T20:27:00","date_gmt":"2021-12-22T20:27:00","guid":{"rendered":"https:\/\/beyondtype2.org\/resources\/como-ayudan-los-medicamentos-a-la-diabetes\/"},"modified":"2021-12-22T20:27:00","modified_gmt":"2021-12-22T20:27:00","slug":"como-ayudan-los-medicamentos-a-la-diabetes","status":"publish","type":"resources","link":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/","title":{"rendered":"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes?"},"content":{"rendered":"<p><em>Este contenido educativo es presentado por&nbsp; <a href=\"https:\/\/beyondtype1.org\/ada-bt1-collab\/\" data-wpel-link=\"internal\" target=\"_blank\" rel=\"noopener noreferrer\">ADA x BT1 Collab<\/a>.<\/em><\/p>\n<hr>\n<p>[bt1-youtube id=&raquo;6LGyNR6xy4o&raquo; type=&raquo;inline&raquo; image=&raquo;&raquo;]<\/p>\n<p><em>Se ha editado la transcripci&oacute;n de la entrevista original en ingl&eacute;s por razones de longitud y claridad<\/em><\/p>\n<p><b>Ginger Vieira: Bienvenidos a las conversaciones de colaboraci&oacute;n con la Asociaci&oacute;n Americana de Diabetes y Beyond Type 1. Mi nombre es Ginger Vieira y hoy estamos hablando con la <\/b><a href=\"https:\/\/translate.google.com\/website?sl=en&amp;tl=es&amp;u=https:\/\/www.diabetes.org\/node\/13846\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Dra. Ruth Weinstock<\/b><\/a><b> , <\/b><a href=\"https:\/\/translate.google.com\/website?sl=en&amp;tl=es&amp;u=https:\/\/www.diabetes.org\/node\/13846\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Presidenta de Medicina y Ciencia de la Asociaci&oacute;n Americana de Diabetes<\/b><\/a><b> .<\/b><\/p>\n<p><b>Dra. Weinstock, gracias por acompa&ntilde;arnos.<\/b><\/p>\n<p><b>Dra. Ruth Weinstock:<\/b><span style=\"font-weight: 400;\"> Gracias por invitarme.<\/span><\/p>\n<p><b>Hoy vamos a explorar un poco sobre los muchos medicamentos para la diabetes que est&aacute;n en el mercado hoy en d&iacute;a y c&oacute;mo funcionan, c&oacute;mo ayudan a reducir los niveles de az&uacute;car en sangre. Hay tantos, Dra. Weinstock, &iquest;por d&oacute;nde empezamos? &iquest;Cu&aacute;l es el primero que se presenta a la mayor&iacute;a de las personas cuando se les diagnostica diabetes Tipo 2?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Por lo general, comenzamos con la metformina que ha sido comprobada, que es gen&eacute;rica, econ&oacute;mica, ha existido durante d&eacute;cadas y sabemos que es segura y efectiva. Por lo que suele ser lo primero que probamos. Pero dependiendo del nivel de glucosa en sangre, as&iacute; como de si las personas tienen otras condiciones m&eacute;dicas, como insuficiencia card&iacute;aca o problemas renales, podr&iacute;amos comenzar con dos medicamentos en el momento del diagn&oacute;stico. Todo depende.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem&aacute;s, si la persona tiene muchos s&iacute;ntomas debido a niveles altos de az&uacute;car en sangre, que pierde peso sin querer, orina mucho, tiene mucha sed y niveles muy altos de az&uacute;car en sangre, entonces podr&iacute;amos comenzar con insulina inicialmente. Con la diabetes Tipo 2, eso no significa que la persona siempre necesitar&aacute; insulina, a diferencia de la diabetes Tipo 1. Pero si los niveles de az&uacute;car en sangre son muy altos y la persona es muy sintom&aacute;tica, entonces el tratamiento con insulina se usar&iacute;a para ayudar a normalizar y luego tratar de hacer la transici&oacute;n a una terapia sin insulina si es posible.<\/span><\/p>\n<p><b>Bajarlos r&aacute;pidamente, porque est&aacute;n en un nivel lo suficientemente alto que hace que sea m&aacute;s peligroso bajarlos gradualmente.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Sol&iacute;amos tener, hace muchos a&ntilde;os, un algoritmo b&aacute;sico, se comienza con este medicamento y luego se pasa a ese medicamento. Ya no hacemos eso. Ahora personalizamos la terapia. Individualizamos la terapia seg&uacute;n la edad, el rango de lecturas de glucosa en sangre, las lecturas de az&uacute;car en sangre y la presencia de otras condiciones m&eacute;dicas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Existen ciertos medicamentos para la diabetes que tambi&eacute;n pueden ayudar si se tiene una enfermedad renal o pueden ayudar con la p&eacute;rdida de peso, etc. Algunos vienen en forma de p&iacute;ldora, algunos son inyecciones diarias o inyecciones una vez a la semana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entonces, como lo mencion&eacute;, dependiendo de la situaci&oacute;n, creo que intentamos personalizarla y encontrar el mejor medicamento posible para esa persona porque con la insulina, por ejemplo, la gente tiende a ganar peso. Entonces, si podemos controlar la diabetes y llevar los niveles a donde queremos con una inyectable una vez a la semana y la metformina, digamos, eso no causa aumento de peso, sino que en realidad ayuda a perder peso y podemos controlar la diabetes. Entonces eso es genial.<\/span><\/p>\n<p><b>El costo de un medicamento tambi&eacute;n es un factor &hellip;<\/b><\/p>\n<p><span style=\"font-weight: 400;\">S&iacute;, la otra consideraci&oacute;n es el costo. Entonces, estos inhibidores de SGLT2 y estos agonistas del receptor de GLP1 que mencion&eacute; son costosos. Son nuevos. Funcionan muy bien, pero algunas personas no pueden pagarlos, lo cual es triste. Una de las cosas que estamos tratando de hacer con la Asociaci&oacute;n Americana de Diabetes es trabajar para garantizar que para todas las personas que necesitan ciertos medicamentos estos sean asequibles y accesibles para que puedan mantenerse saludables. Pero, lamentablemente, en este momento ese no es el caso de muchas personas, tienen planes con deducibles altos o tienen copagos altos o no tienen seguro por una variedad de razones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entonces, en esos casos, no queremos recetar algo que no pueden pagar y que luego no se administran o que lo racionan y entonces eso no funciona bien. Entonces no se logra el&nbsp; prop&oacute;sito. Si un paciente realmente no puede pagar otras opciones, existe un medicamento m&aacute;s antiguo, las sulfonilureas, que tambi&eacute;n son extremadamente econ&oacute;micas, al igual que la metformina es extremadamente econ&oacute;mica. Funciona muy bien para reducir los niveles de glucosa en sangre. Y eso puede ser algo que se usar&iacute;a en alguien que tiene problemas para pagar sus medicamentos.<\/span><\/p>\n<p><b>Entonces, volviendo a la metformina, &iquest;podr&iacute;a decirme lo esencial de c&oacute;mo ayuda a reducir el az&uacute;car en sangre?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Bien, la metformina act&uacute;a de varias formas, pero la principal es en el h&iacute;gado. Entonces, en la diabetes Tipo 2, para muchas personas, el h&iacute;gado, cuando duerme, especialmente durante la noche, produce demasiada az&uacute;car. De hecho, fabrica glucosa y la metformina ayuda a suprimir eso para que uno no se despierte con niveles altos de az&uacute;car en sangre. Esa es una de las principales formas en que funciona.<\/span><\/p>\n<p><b>Bueno. Y luego los inhibidores de SGLT2. &iquest;C&oacute;mo ayudan a reducir los niveles de az&uacute;car en sangre?&nbsp;<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Normalmente, el ri&ntilde;&oacute;n, cuando el nivel de az&uacute;car en la sangre es alto, filtra la glucosa y luego la reabsorbe, la devuelve al cuerpo y estos medicamentos bloquean esa reabsorci&oacute;n. As&iacute; que b&aacute;sicamente se elimina algo de esa az&uacute;car a trav&eacute;s de la orina. Entonces, al orinar, la orina contiene m&aacute;s az&uacute;car y se deshace de ella a trav&eacute;s de ese mecanismo. Esa es la principal forma en que funcionan.<\/span><\/p>\n<p><b>Bueno. Y luego tenemos los agonistas de GLP-1.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El agonista del receptor de GLP-1, es una clase de f&aacute;rmacos muy interesante. Entonces, resulta que cuando uno come, cuando el tracto gastrointestinal y los intestinos ven los nutrientes de la comida, le indican al p&aacute;ncreas que secrete insulina adicional. Entonces, si yo te diera glucosa directamente en la sangre en lugar de que la comas, el p&aacute;ncreas arrojar&iacute;a insulina adicional cuando esa comida pasara por los intestinos. Normalmente, hay un aumento de esta hormona llamada GLP-1 que se estimula cuando uno come.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por lo tanto, hay ciertas c&eacute;lulas en los intestinos que secretan una hormona de muy corta duraci&oacute;n llamada GLP-1 que hace que el p&aacute;ncreas arroje m&aacute;s insulina en respuesta a la comida. Tambi&eacute;n suprime una hormona llamada <\/span><a href=\"https:\/\/beyondtype2-org.translate.goog\/glucagon\/?_x_tr_sl=en&amp;_x_tr_tl=es&amp;_x_tr_hl=en-US\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">glucag&oacute;n<\/span><\/a><span style=\"font-weight: 400;\"> que act&uacute;a de forma opuesta a la insulina. El glucag&oacute;n aumenta el az&uacute;car en sangre y puede hacer que uno se sienta un poco m&aacute;s lleno al hacer un poco m&aacute;s lenta la digesti&oacute;n, lo que tambi&eacute;n ayuda a perder peso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entonces, en las personas con diabetes Tipo 2, muchas de ellas tienen deficiencia de esta hormona. Y entonces, este agonista inyectable del receptor de GLP-1, en realidad ahora tambi&eacute;n est&aacute; disponible en forma de p&iacute;ldora, que b&aacute;sicamente lo que hace es reemplazar la deficiencia del GLP-1.<\/span><\/p>\n<p><b>Bueno. Entonces esas son las primeras tres categor&iacute;as.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Y luego los medicamentos de sulfonilurea, que han existido por mucho tiempo, est&aacute;n disponibles en opciones gen&eacute;ricas y estimulan directamente al p&aacute;ncreas para que arroje lo que haya extra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero a diferencia del GLP-1, es un aumento m&aacute;s constante en la producci&oacute;n de insulina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tienen una acci&oacute;n m&aacute;s prolongada, por lo que los medicamentos con sulfonilurea, si se toman en exceso (en particular, las personas mayores son m&aacute;s propensas a esto), el nivel de az&uacute;car en sangre puede bajar demasiado, que es lo que llamamos hipoglucemia. Mientras que eso no es com&uacute;n con el agonista del receptor de GLP-1. Adem&aacute;s, las sulfonilureas son neutrales en cuanto al peso o causan un poco de aumento de peso, mientras que el agonista del receptor de GLP-1, debido a esos otros efectos sobre la sensaci&oacute;n de saciedad y sobre el est&oacute;mago y sobre el glucag&oacute;n, en realidad generalmente causa p&eacute;rdida de peso.<\/span><\/p>\n<p><b>&iquest;Y los inhibidores de DPP4 ser&iacute;an los siguientes de los cinco primeros?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los inhibidores de DPP4. Ya mencion&eacute; el GLP-1. Esa es la hormona que cuando se ingiere alimentos, los nutrientes en el sistema digestivo, en los intestinos, hacen que esas c&eacute;lulas en los intestinos expulsen GLP-1, esa hormona, que es de corta duraci&oacute;n y hace que el p&aacute;ncreas secrete algo de insulina extra. Resulta que el GLP-1 nativo, el GLP-1 que tu cuerpo produce normalmente, tiene una vida media muy, muy corta, que luego de un per&iacute;odo de tiempo muy, muy corto, unos minutos, se metaboliza. Es degradado por una enzima llamada DPP4.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entonces, lo que hace esta p&iacute;ldora, los inhibidores de la DPP4, es que evita parcialmente que el nativo, el GLP-1 que t&uacute; mismo fabricas, se descomponga tan r&aacute;pido. Para que se puedan elevar esos niveles. No se logran niveles tan altos como con el agonista del receptor de GLP-1 inyectable, pero son seguros. Por lo general, no est&aacute;n asociados con hipoglucemia, niveles bajos de az&uacute;car en sangre. Y suelen ser bastante bien tolerados. No reducen tanto el A1c y no provocan p&eacute;rdida de peso, pero tampoco provocan aumento de peso.<\/span><\/p>\n<p><b>Bien, y es importante que uno sepa que si un tipo de medicamento para la diabetes en una determinada clase de medicamento no est&aacute; funcionando por cualquier motivo, tiene efectos secundarios o simplemente no ayuda a que los niveles de az&uacute;car en sangre est&eacute;n dentro del rango, uno debe hablar con el m&eacute;dico sobre hacer el intento con otra cosa.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Absolutamente. Entonces, a medida que aprendamos m&aacute;s sobre la diabetes y se realicen m&aacute;s investigaciones, lo que ahora llamamos diabetes Tipo 2 terminar&aacute; siendo m&uacute;ltiples tipos de diabetes. Porque, como ya sabemos, es muy heterog&eacute;neo, y predigo que en el futuro habr&aacute; un an&aacute;lisis de sangre que dir&aacute; que necesitas un GLP-1. Y no lo necesitar&aacute;s, de hecho, eso ni siquiera funcionar&aacute; en ti, debes usar metformina. Y para otra persona, la metformina no funcionar&aacute;, por lo que debe usar esto. As&iacute; que creo que podremos personalizarlo bas&aacute;ndonos en la gen&eacute;tica y el tipo real de diabetes que tiene esa persona. Pero ahora mismo no tenemos ese conocimiento y no tenemos esas pruebas. Entonces, lo mejor que podemos hacer ahora es comenzar con lo que tenga m&aacute;s sentido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero si los niveles de az&uacute;car en sangre no est&aacute;n dentro del objetivo, se debe agregar algo m&aacute;s. Si el medicamento que uno est&aacute; tomando no hizo una diferencia, los niveles de az&uacute;car en sangre no cambiaron cuando se comenz&oacute; ese medicamento y ahora est&aacute; recetado y se lo est&aacute; tomando, se debe dejar de tomar ese medicamento y probar uno diferente. Si ayud&oacute;, entonces tal vez se necesite otro medicamento adicional. Entonces, cada persona responder&aacute; de diferentes maneras. Y todo eso debe hablarse con el proveedor de atenci&oacute;n m&eacute;dica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se vuelve muy complejo porque hay tantas opciones maravillosas que tenemos ahora y m&aacute;s y m&aacute;s en el futuro, incluidas m&aacute;s y m&aacute;s insulinas. Por lo tanto, si uno ha probado todas las terapias sin insulina y a&uacute;n no ha alcanzado el objetivo, es posible que se necesite una terapia con insulina.<\/span><\/p>\n<p><b>Bueno. Es realmente valioso saber que todos funcionan de manera tan diferente. Entonces, si uno no est&aacute; funcionando, no es que todos estos medicamentos sean in&uacute;tiles, es que no se ha encontrado el correcto que realmente aborde el problema correcto, que podr&iacute;a ayudarlo a uno.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Correcto. Y <\/span><a href=\"https:\/\/beyondtype2-org.translate.goog\/when-to-check-blood-sugar\/?_x_tr_sl=en&amp;_x_tr_tl=es&amp;_x_tr_hl=en-US\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">controlar el nivel de az&uacute;car en sangre generalmente con un medidor de glucosa<\/span><\/a><span style=\"font-weight: 400;\"> o un <\/span><a href=\"https:\/\/translate.google.com\/website?sl=en&amp;tl=es&amp;u=https:\/\/beyondtype1.org\/cgm-continuous-glucose-monitor\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">monitor continuo de glucosa<\/span><\/a><span style=\"font-weight: 400;\"> es realmente importante. No podemos saber si los medicamentos est&aacute;n funcionando bien si no sabemos cu&aacute;l es el nivel de az&uacute;car en sangre.<\/span><\/p>\n<p><b>Muchas gracias por ese nivel tan alto, pero a la vez con una explicaci&oacute;n simplificada de todas las opciones en el mercado hoy.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ha sido un gusto.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/beyondtype1.org\/es\/wp-content\/uploads\/2021\/04\/GingerVieira.HeadShot.Scaled.png<\/p>\n<p>Ginger Vieira es una autora y escritora que vive con diabetes Tipo 1, enfermedad cel&iacute;aca, fibromialgia e hipotiroidismo. Es autora de una variedad de libros, incluidos &laquo;When I Go Low&raquo; (Cuando tengo un nivel bajo) (para ni&ntilde;os), &laquo;Pregnancy with Type 1 Diabetes&raquo; (El embarazo con diabetes Tipo 1) y &laquo;Dealing with Diabetes Burnout&raquo; (Lidiando con el s&iacute;ndrome de burnout por la diabetes). Ginger tambi&eacute;n ha escrito para Diabetes Mine, Healthline, T1D Exchange, Diabetes Strong y m&aacute;s. En su tiempo libre le gusta saltar la cuerda, andar en monopat&iacute;n con sus hijas o caminar con su chico guapo y su perro.<\/p>\n<p>collabconversations|resource<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Este contenido educativo es presentado por&nbsp; ADA x BT1 Collab. [bt1-youtube id=&raquo;6LGyNR6xy4o&raquo; type=&raquo;inline&raquo; image=&raquo;&raquo;] Se ha editado la transcripci&oacute;n de la entrevista original en ingl&eacute;s por razones de longitud y claridad Ginger Vieira: Bienvenidos a las conversaciones de colaboraci&oacute;n con la Asociaci&oacute;n Americana de Diabetes y Beyond Type 1. Mi nombre es Ginger Vieira y [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":31862,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-31860","resources","type-resources","status-publish","has-post-thumbnail","hentry","diabetes-types-tipo-2","tags-collabconversations"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes? | Beyond Type 1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes? | Beyond Type 1\" \/>\n<meta property=\"og:description\" content=\"Este contenido educativo es presentado por&nbsp; ADA x BT1 Collab. [bt1-youtube id=&raquo;6LGyNR6xy4o&raquo; type=&raquo;inline&raquo; image=&raquo;&raquo;] Se ha editado la transcripci&oacute;n de la entrevista original en ingl&eacute;s por razones de longitud y claridad Ginger Vieira: Bienvenidos a las conversaciones de colaboraci&oacute;n con la Asociaci&oacute;n Americana de Diabetes y Beyond Type 1. Mi nombre es Ginger Vieira y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Type 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beyondtype1\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeyondType1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/\",\"name\":\"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes? | Beyond Type 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png\",\"datePublished\":\"2021-12-22T20:27:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png\",\"width\":1200,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/como-ayudan-los-medicamentos-a-la-diabetes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"name\":\"Beyond Type 1\",\"description\":\"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\",\"name\":\"Beyond Type 1\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"width\":56,\"height\":56,\"caption\":\"Beyond Type 1\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beyondtype1\",\"https:\\\/\\\/x.com\\\/BeyondType1\",\"http:\\\/\\\/instagram.com\\\/BeyondType1\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/BeyondType1\",\"https:\\\/\\\/www.tiktok.com\\\/@beyondtype1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beyond-type1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes? | Beyond Type 1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes? | Beyond Type 1","og_description":"Este contenido educativo es presentado por&nbsp; ADA x BT1 Collab. [bt1-youtube id=&raquo;6LGyNR6xy4o&raquo; type=&raquo;inline&raquo; image=&raquo;&raquo;] Se ha editado la transcripci&oacute;n de la entrevista original en ingl&eacute;s por razones de longitud y claridad Ginger Vieira: Bienvenidos a las conversaciones de colaboraci&oacute;n con la Asociaci&oacute;n Americana de Diabetes y Beyond Type 1. Mi nombre es Ginger Vieira y [&hellip;]","og_url":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/","og_site_name":"Beyond Type 1","article_publisher":"https:\/\/www.facebook.com\/beyondtype1","og_image":[{"width":1200,"height":430,"url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BeyondType1","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/","url":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/","name":"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes? | Beyond Type 1","isPartOf":{"@id":"https:\/\/beyondtype1.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/#primaryimage"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/#primaryimage"},"thumbnailUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png","datePublished":"2021-12-22T20:27:00+00:00","breadcrumb":{"@id":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/#primaryimage","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2024\/11\/BT1-HOW-ARE-THESE-DIABETES-MEDICATIONS-HEADER-1.png","width":1200,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/beyondtype1.org\/es\/como-ayudan-los-medicamentos-a-la-diabetes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondtype1.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo ayudan estos medicamentos al manejo de mi diabetes?"}]},{"@type":"WebSite","@id":"https:\/\/beyondtype1.org\/es\/#website","url":"https:\/\/beyondtype1.org\/es\/","name":"Beyond Type 1","description":"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.","publisher":{"@id":"https:\/\/beyondtype1.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondtype1.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/beyondtype1.org\/es\/#organization","name":"Beyond Type 1","url":"https:\/\/beyondtype1.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","width":56,"height":56,"caption":"Beyond Type 1"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondtype1","https:\/\/x.com\/BeyondType1","http:\/\/instagram.com\/BeyondType1\/","https:\/\/www.youtube.com\/c\/BeyondType1","https:\/\/www.tiktok.com\/@beyondtype1","https:\/\/www.linkedin.com\/company\/beyond-type1\/"]}]}},"_links":{"self":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/31860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/comments?post=31860"}],"version-history":[{"count":0,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/31860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media\/31862"}],"wp:attachment":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media?parent=31860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}