{"id":35217,"date":"2016-01-10T18:42:36","date_gmt":"2016-01-10T18:42:36","guid":{"rendered":"https:\/\/beyondtype2.org\/salud-emocional-y-diabetes-una-conversacion-necesaria\/"},"modified":"2024-12-17T16:33:23","modified_gmt":"2024-12-17T16:33:23","slug":"salud-emocional-y-diabetes-una-conversacion-necesaria","status":"publish","type":"resources","link":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/","title":{"rendered":"Salud emocional y diabetes: una conversaci\u00f3n necesaria"},"content":{"rendered":"<p><b><i>Nota del editor:<\/i><\/b> <i><span style=\"font-weight: 400;\">Este contenido educativo es posible gracias a la<\/span><\/i> <a href=\"https:\/\/beyondtype1.org\/ada-bt1-collab\/\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\">colaboraci&oacute;n ADA x BT1<\/span><\/i><\/a> <i><span style=\"font-weight: 400;\">y se public&oacute; originalmente en espa&ntilde;ol en<\/span><\/i> <a href=\"https:\/\/es.beyondtype1.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"><i><span style=\"font-weight: 400;\">es.beyondtype1.org<\/span><\/i><\/a> <i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p>\n<hr>\n<p><span style=\"font-weight: 400;\">La Dra. Cynthia Mu&ntilde;oz, psic&oacute;loga certificada y profesora adjunta de pediatr&iacute;a cl&iacute;nica, obtuvo su doctorado en psicolog&iacute;a cl&iacute;nica y actualmente trabaja como psic&oacute;loga pedi&aacute;trica en el centro de salud mental del Hospital Infantil de Los &Aacute;ngeles y en el CDM (Centro de Endocrinolog&iacute;a, Diabetes y Metabolismo). La Dra. Mu&ntilde;oz es investigadora y ha co-desarrollado un programa social para adolescentes con diabetes tipo 1. Tambi&eacute;n es miembro del <\/span><a href=\"https:\/\/www.diabetes.org\/healthy-living\/mental-health?&amp;ada_source=WWP211001LW001M001CC&amp;ada_sub_source=google&amp;utm_source=google&amp;utm_medium=search&amp;utm_campaign=awareness-campaign&amp;utm_term=one-time&amp;utm_content=ad&amp;autologin=true&amp;s_src=AAP181101LXXXXM001CC%E2%80%9D&amp;gclid=Cj0KCQiAoNWOBhCwARIsAAiHnEjD-ypTsBcoJrEYG8f7LeIb1nZqRCkPipUOrqGOqVkporYho50JAokaApkpEALw_wcB&amp;gclsrc=aw.ds\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Comit&eacute; directivo del Programa de Educaci&oacute;n sobre Diabetes y Salud Mental de la Asociaci&oacute;n Estadounidense de Diabetes<\/span><\/a> <span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando nos reunimos con el Dr. Mu&ntilde;oz, hablamos sobre la salud emocional y la diabetes. En ese momento, la conversaci&oacute;n fue particularmente fascinante considerando las complejidades emocionales de la temporada navide&ntilde;a que rodean el manejo de la diabetes. <\/span><\/p>\n<p><b>BT1: En primer lugar, la pregunta m&aacute;s frecuente es: &iquest;a qu&eacute; nos referimos exactamente cuando hablamos de salud mental? &iquest;Qu&eacute; es la salud mental? <\/b><\/p>\n<p><b>Dra. Cynthia Mu&ntilde;oz: <\/b><span style=\"font-weight: 400;\">&iexcl;Buena pregunta! Hay muchas cosas, pero una definici&oacute;n que le&iacute; y que creo que lo refleja es que la salud mental incluye el bienestar emocional, psicol&oacute;gico y social. Afecta la forma en que pensamos, sentimos y actuamos. Ayuda a determinar c&oacute;mo manejamos el estr&eacute;s, nos relacionamos con los dem&aacute;s y tomamos decisiones. Es algo que afecta, bueno&hellip; a todo. <\/span><\/p>\n<p><b>Cuando hablamos de controlar todos los tipos de diabetes, a menudo pensamos en la relaci&oacute;n biopsicosocial (biol&oacute;gica, psicol&oacute;gica, social y ambiental) que tenemos con ella. Lamentablemente, no solemos poner tanto &eacute;nfasis en la salud mental. &iquest;Qu&eacute; relaci&oacute;n reconocemos actualmente entre la salud mental o emocional y la diabetes de cualquier tipo? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Lo que s&iacute; sabemos es que la salud mental afecta a muchos aspectos o a todos los aspectos de la vida diaria, como la forma en que pensamos, c&oacute;mo nos sentimos y c&oacute;mo manejamos el estr&eacute;s. La diabetes tambi&eacute;n requiere una gran toma de decisiones, y sabemos que existe una conexi&oacute;n entre el estr&eacute;s y los niveles de glucosa en sangre. Los sentimientos, los pensamientos, las creencias y las actitudes&hellip; Es decir, muchas cosas pueden afectar la salud de nuestro cuerpo. Los problemas o desaf&iacute;os relacionados con la salud mental pueden afectar a la diabetes, y los problemas relacionados con la diabetes pueden empeorar los desaf&iacute;os existentes relacionados con la salud mental o de otro tipo. Existe una conexi&oacute;n entre la diabetes y la salud mental y viceversa. <\/span><\/p>\n<p><b>Por supuesto. Estos desaf&iacute;os est&aacute;n directamente relacionados con muchas personas que viven con diabetes. Por ejemplo, yo vivo con diabetes tipo 1. La respuesta de mi cuerpo al miedo, el estr&eacute;s, la alegr&iacute;a y la emoci&oacute;n es bastante evidente en mi caso. Parece que no siempre somos conscientes de que estas emociones afectar&aacute;n directamente nuestros niveles de glucosa en sangre. Por lo tanto, es imperativo que tambi&eacute;n cuidemos nuestra salud emocional, al igual que nuestros niveles de glucosa en sangre, la dieta y los ejercicios. En los ni&ntilde;os, &iquest;esta respuesta se magnifica? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">S&iacute;. Como lo que acabas de mencionar, creo que algo fundamental que hay que reconocer es que las emociones nos afectan: lo que sentimos, pensamos y hacemos. Pero el impacto es diferente para cada persona. Cuando hablamos de j&oacute;venes con diabetes, puede ser que un joven que est&aacute; bajo mucho estr&eacute;s vea un cambio en sus niveles de glucosa en sangre; puede ser que esos niveles de glucosa en sangre suban o bajen. Depende del tipo de estr&eacute;s y de c&oacute;mo la persona maneje la situaci&oacute;n o sus emociones. Los ni&ntilde;os todav&iacute;a est&aacute;n aprendiendo a identificar lo que sienten, por qu&eacute; una situaci&oacute;n los afecta, por qu&eacute; se sienten como se sienten, qu&eacute; significan sus sentimientos y qu&eacute; tiene que ver todo esto con su diabetes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los ni&ntilde;os dependen m&aacute;s que los adultos de los sistemas de apoyo externos, como los cuidadores, los amigos y la familia. Los adultos tienen una mayor percepci&oacute;n de sus sentimientos y de c&oacute;mo estos afectan a sus niveles de az&uacute;car en sangre. Tienen m&aacute;s control sobre sus emociones. Por lo tanto, en el caso de los ni&ntilde;os, tiene sentido que los cuidadores tengan mucho que ver con saber c&oacute;mo las emociones de un ni&ntilde;o afectan a sus niveles de glucosa en sangre. Los cuidadores tienen un papel m&aacute;s activo a la hora de ayudar a los ni&ntilde;os a responder a los cambios en los niveles de glucosa en sangre afectados por las emociones. <\/span><\/p>\n<p><b>Durante las vacaciones, quienes viven con diabetes tienden a estresarse un poco m&aacute;s. &iquest;Por qu&eacute; parece que estamos m&aacute;s estresados cuando vivimos con diabetes? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Bueno, con la diabetes, suele haber un poco m&aacute;s de estr&eacute;s en las fiestas porque hay varias cosas que cambian, como los horarios. Muchas personas est&aacute;n de vacaciones. Otras no tienen descanso y algunas pasan m&aacute;s tiempo en casa de lo habitual. Estas din&aacute;micas pueden afectar el estr&eacute;s y, por lo tanto, los niveles de glucosa en sangre. Los horarios de las comidas cambian y los alimentos disponibles para nosotros tambi&eacute;n cambian. Los horarios de sue&ntilde;o tambi&eacute;n pueden variar. Muchas cosas suceden durante esta temporada que normalmente no son parte de nuestras rutinas durante el resto del a&ntilde;o, lo que genera estr&eacute;s. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante las vacaciones, suele ser m&aacute;s f&aacute;cil para los adultos decir no a ciertos alimentos o permitirse ciertos caprichos. Tienen m&aacute;s experiencia que los ni&ntilde;os en el manejo de alimentos que afectan dr&aacute;sticamente los niveles de glucosa en sangre. Con los ni&ntilde;os, es muy diferente. Es posible que no entiendan lo que les pedimos que hagan durante las vacaciones, ya sea controlar sus niveles de glucosa en sangre frente a rutinas o alimentos anormales o decir no a ciertos alimentos. Es dif&iacute;cil. Los ni&ntilde;os quieren comer y jugar y no pensar tanto en los l&iacute;mites. Sin mencionar que nuestra nueva normalidad (la pandemia) presenta una bola curva adicional. <\/span><\/p>\n<p><b>Exactamente, la &ldquo;nueva normalidad&rdquo; en la que nos encontramos ha provocado un estr&eacute;s sin precedentes que afecta el control de la diabetes. &iquest;Existen se&ntilde;ales o s&iacute;ntomas de advertencia que nos indiquen que debemos buscar ayuda? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">&iexcl;S&iacute;! Es fundamental que las personas con diabetes y los padres de ni&ntilde;os con diabetes mantengan la comunicaci&oacute;n con su equipo de salud. Cuando te das cuenta de que el estr&eacute;s ya est&aacute; afectando tu rutina diaria, el sue&ntilde;o y el apetito, te sientes muy irritado, lo que afecta tu comunicaci&oacute;n con tus seres queridos. Cuando se presentan este tipo de situaciones, sabes que es momento de buscar la ayuda de un profesional. <\/span><\/p>\n<p><b>En la comunidad de la diabetes existe la falsa suposici&oacute;n de que tenemos acceso directo a expertos y relaciones con ellos que pueden ayudarnos en nuestro camino hacia la salud emocional, pero ese no siempre es el caso. &iquest;C&oacute;mo pueden las personas con diabetes y sus cuidadores obtener el apoyo emocional que necesitan, principalmente durante las fiestas? Los cuidadores de ni&ntilde;os con diabetes tipo 1 tambi&eacute;n pueden necesitar ayuda emocional que no est&aacute;n recibiendo. &iquest;Puede hablarnos al respecto? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Por supuesto. Para algunos padres, es impactante recibir la noticia de que sus hijos han sido&hellip; <\/span><a href=\"https:\/\/beyondtype1.org\/warning-signs-of-type-1-diabetes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">diagnosticado con diabetes<\/span><\/a><span style=\"font-weight: 400;\">. Especially among newly-diagnosed families, there can be emotional trauma. <\/span><a href=\"https:\/\/beyondtype1.org\/celebrations-holidays\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Navegando las vacaciones<\/span><\/a><span style=\"font-weight: 400;\"> El hecho de estar rodeado de un diagn&oacute;stico de diabetes tipo 1 puede hacer que la temporada sea m&aacute;s dif&iacute;cil para todos. Durante la &eacute;poca navide&ntilde;a, por ejemplo, hay muchas fiestas y comidas deliciosas que pueden obligarlo a pensar en c&oacute;mo se siente su ser querido que est&aacute; controlando la diabetes. Es posible que se pregunte c&oacute;mo lo afectan los eventos de las fiestas. Es esencial empatizar y reconocer c&oacute;mo se sienten usted y los dem&aacute;s. Mientras tanto, las fiestas deber&iacute;an ser un per&iacute;odo de felicidad: hay mucho que procesar. <\/span><\/p>\n<p><b>&iquest;Qui&eacute;nes son nuestros expertos en salud emocional?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Expertos en<\/span> <a href=\"https:\/\/beyondtype1.org\/diabetes-diagnosed-mental-health\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">salud emocional<\/span><\/a><span style=\"font-weight: 400;\"> Los psic&oacute;logos de la actualidad est&aacute;n formados por todos los profesionales que ayudan a las familias a afrontar la diabetes. Los m&eacute;dicos y enfermeros de hoy tambi&eacute;n deben tener en cuenta la salud f&iacute;sica, social y emocional. Son conscientes de la experiencia de la diabetes, pero algunos psic&oacute;logos se especializan en la vida con diabetes y en c&oacute;mo afecta a nuestra salud mental. Como resultado, pueden atender a las personas con diabetes de manera m&aacute;s eficaz. Los expertos en salud mental trabajan con todo tipo de personas. Cuando hablo con familias reci&eacute;n diagnosticadas y me presento como psic&oacute;logo en un centro de diabetes, menciono que trabajo con familias &laquo;normales&raquo; porque, como psic&oacute;logo, muchas personas dicen que solo trabajamos con personas &laquo;locas&raquo;. Yo me especializo en personas con diabetes. <\/span><\/p>\n<p><b>&iquest;C&oacute;mo pueden y deben los cuidadores cuidar su salud emocional? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">Cuando alguien tiene diabetes, es importante preguntarle: &laquo;&iquest;C&oacute;mo puedo ayudarle?&raquo;. A menudo pensamos que ya sabemos lo que necesita la persona, pero no siempre es as&iacute;. Necesitamos identificar las necesidades individuales. Otras partes esenciales del manejo de la salud emocional son planificar las comidas y los horarios, identificar qu&eacute; suministros necesitar&aacute;s llevar para cualquier viaje, saber qu&eacute; hacer durante una fiesta si los niveles de az&uacute;car en sangre est&aacute;n descontrolados, ayudar a los ni&ntilde;os con el conteo de carbohidratos, etc. Podemos pensar que <\/span><a href=\"https:\/\/beyondtype1.org\/teens-with-type-1-depression\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">adolescentes<\/span><\/a><span style=\"font-weight: 400;\"> Ya sabemos lo que est&aacute;n haciendo, pero debemos recordar que son ni&ntilde;os y que a&uacute;n pueden necesitar nuestra ayuda. Debemos cuidar de nosotros mismos y de los dem&aacute;s, evitando el estr&eacute;s mediante la planificaci&oacute;n. Deber&iacute;amos tener un plan para manejar problemas inesperados relacionados con la diabetes, como <\/span><a href=\"https:\/\/beyondtype1.org\/hypoglycemia-and-how-to-treat-it\/#:~:text=It%20is%20defined%20as%20a,seizures%2C%20unconsciousness%20and%20sometimes%20death.\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">hipoglucemia<\/span><\/a><span style=\"font-weight: 400;\">. We need to know how to manage it and how to communicate. These are important mental health considerations, not just for individuals with diabetes <\/span><a href=\"\/?p=8814\"><span style=\"font-weight: 400;\">pero para sus cuidadores<\/span><\/a><span style=\"font-weight: 400;\">. We need to take care of people with diabetes and their caregivers. <\/span><\/p>\n<p><b>&iquest;Existe alguna manera de lidiar con el estr&eacute;s o debemos aprender a vivir con la diabetes y el estr&eacute;s?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">S&iacute;. Debemos aprender a vivir con la diabetes y el estr&eacute;s porque en la vida hay estr&eacute;s. Puede ser negativo o positivo, como una fiesta. Una fiesta, con suerte, ser&iacute;a un estr&eacute;s bueno. Si tratamos de evitar que el estr&eacute;s exista o no lo enfrentamos, eso tambi&eacute;n puede afectarnos negativamente. Es bueno reconocer esto hablando abiertamente sobre el autocuidado y los niveles de estr&eacute;s. La diabetes es 25\/8, no 24\/7. Estar f&iacute;sicamente activo, hacer ejercicio, meditar, practicar yoga, tomar descansos y respirar aire fresco puede parecer algo peque&ntilde;o, pero nos ayuda. <\/span><a href=\"https:\/\/beyondtype1.org\/stress-why-and-how-you-should-reduce-it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Manejar<\/span><\/a> <span style=\"font-weight: 400;\">mucho el estr&eacute;s.<\/span><\/p>\n<p><b>&iquest;Qu&eacute; consejo le dar&iacute;as a los padres que se estresan por los niveles de glucosa en sangre de sus hijos?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Los padres aman a sus hijos y quieren protegerlos, asegur&aacute;ndose de que est&eacute;n bien. Es muy importante reflexionar sobre esto. Cuando ves un nivel de glucosa en sangre muy alto o muy bajo, es normal que te sientas preocupado y estresado como padre. Como padres, podemos preguntarnos: &iquest;Qu&eacute; pas&oacute;? &iquest;Qu&eacute; hiciste? Estamos tratando de encontrar el glucag&oacute;n, Baqsimi, para los niveles bajos de az&uacute;car en sangre. Nos preocupamos mucho. Es importante mantener la calma, respirar profundamente y ver la lectura del nivel de az&uacute;car en sangre como una informaci&oacute;n. Luego, se trata de saber qu&eacute; hacer. <\/span><a href=\"https:\/\/beyondtype1.org\/hyperglycemia-and-how-to-treat-it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">&iquest;Cu&aacute;nta insulina se administra cuando hay un nivel alto de az&uacute;car en sangre?<\/span><\/a> <span style=\"font-weight: 400;\">&iquest;Se<\/span> <a href=\"https:\/\/beyondtype1.org\/hypoglycemia-and-how-to-treat-it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">trata un nivel bajo de az&uacute;car en sangre con una pastilla de glucosa o jugo?<\/span><\/a><span style=\"font-weight: 400;\"> Intente concentrarse en lo que necesita hacer para restablecer los niveles de glucosa en sangre. Mantener un <\/span><a href=\"\/?p=28464\"><span style=\"font-weight: 400;\">tono de voz neutral<\/span><\/a><span style=\"font-weight: 400;\"> Es algo que menciono todo el tiempo cuando hablo con padres y cuidadores. Debes ponerlo en pr&aacute;ctica. En algunas situaciones, puedes reaccionar, pero no pasa nada. Date cuenta de ello y dite a ti mismo: si esto vuelve a suceder, respirar&eacute; profundamente y har&eacute; lo que tenga que hacer para controlar la glucosa en sangre. <\/span><\/p>\n<p><b>Como cuidadores, &iquest;c&oacute;mo podemos identificar que estamos experimentando depresi&oacute;n y no solo un momento de tristeza?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La depresi&oacute;n tiene que ver con la tristeza. La diferencia significativa con la depresi&oacute;n es que comienzas a notar un impacto en los niveles de energ&iacute;a. Puedes tener m&aacute;s dificultad para levantarte por la ma&ntilde;ana y experimentar cambios en el apetito y el sue&ntilde;o. Con la depresi&oacute;n, algunas personas duermen m&aacute;s o menos de lo habitual. Si comienzas a notar estos cambios, habla con tu m&eacute;dico. Cu&eacute;ntale c&oacute;mo te sientes para que pueda ayudarte a identificar si lo que est&aacute;s experimentando es depresi&oacute;n o algo m&aacute;s. A partir de ah&iacute;, puedes formular un plan. Puedes intentar diagnosticarte a ti mismo buscando en Internet tus s&iacute;ntomas, pero siempre es mejor consultar a un profesional para que haga un diagn&oacute;stico oficial. <\/span><\/p>\n<p><b>&iquest;Pueden los ni&ntilde;os con diabetes desarrollar depresi&oacute;n?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">S&iacute;. Los ni&ntilde;os con diabetes tienen un riesgo mayor de sufrir depresi&oacute;n que los ni&ntilde;os que no tienen diabetes. Si le preocupa que su hijo pueda estar deprimido, observe atentamente su apetito, sus niveles de energ&iacute;a y su productividad en la escuela. Si nota que sus notas bajan, preste atenci&oacute;n y hable con su hijo. Puede ser una se&ntilde;al de advertencia de depresi&oacute;n. Muchas veces, la gente piensa que los ni&ntilde;os no pueden estar deprimidos. Sin embargo, cuando observamos nuestra infancia como adultos, entendemos que los ni&ntilde;os pueden estar deprimidos. Podemos empatizar con nuestros hijos cuando consideramos nuestras propias experiencias en la juventud. Es posible que los ni&ntilde;os se depriman porque cada persona es diferente. La depresi&oacute;n es incre&iacute;blemente personal. <\/span><\/p>\n<p><b>En el caso de las personas con diabetes, no solo se habla de estr&eacute;s como un problema, sino tambi&eacute;n de angustia por diabetes. &iquest;Qu&eacute; es la angustia por diabetes y en qu&eacute; se diferencia del estr&eacute;s? <\/b><\/p>\n<p><span style=\"font-weight: 400;\">El t&eacute;rmino angustia por diabetes tiene que ver con el impacto que tiene el control de la diabetes en su vida. Con la diabetes tipo 1, ya sabemos que se controla el nivel de az&uacute;car en sangre y se observan muchas cosas durante todo el d&iacute;a. Hay tantas cosas que las personas con diabetes tienen que controlar todos los d&iacute;as. Estas peque&ntilde;as cargas pueden afectar a una persona con el tiempo, provocando <\/span><a href=\"https:\/\/beyondtype1.org\/diabetes-burnout\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">agotamiento<\/span><\/a> <span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><b>Finalmente, en BT1, sabemos que la ADA ha estado trabajando muy duro durante varios a&ntilde;os en la salud emocional, por lo que nos preguntamos: &iquest;qu&eacute; veremos de la ADA en los pr&oacute;ximos meses o a&ntilde;os?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Continuaremos con este trabajo. Nos centramos en las personas y reconocemos que la salud mental es integral. No podemos evitar este tema cuando hablamos de cuidar a una persona con diabetes. Tenemos un <\/span><a href=\"https:\/\/professional.diabetes.org\/ada-mental-health-provider-directory\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Portal de recursos donde las personas con diabetes pueden buscar terapeutas<\/span><\/a> <span style=\"font-weight: 400;\">o<\/span> <a href=\"https:\/\/beyondtype1.org\/t1d-guide-mental-health-care-providers\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">profesionales de la salud mental.<\/span><\/a><span style=\"font-weight: 400;\">, que se especializan o tienen conocimientos sobre diabetes. Esa lista de especialistas seguir&aacute; creciendo. Tambi&eacute;n tenemos una gran cantidad de materiales que se centran en la salud mental y la diabetes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mencionaste otros recursos, por ejemplo,<\/span> <a href=\"https:\/\/www.diabetes.org\/community\/camp\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">los campamentos de diabetes.<\/span><\/a><span style=\"font-weight: 400;\">. This is another project that continues to grow. Another project I love is <\/span><a href=\"https:\/\/www.diabetes.org\/community\/project-power\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Proyecto Poder<\/span><\/a><span style=\"font-weight: 400;\">. It is a program that offers information about mental health, emotional and social conditions and opportunities for physical activity. There are many things we have to keep doing for people with diabetes. We want to keep making it easy for them to find mental health professionals with knowledge about diabetes. I know that <\/span><a href=\"https:\/\/beyondtype1.org\/mental-health\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Beyond Type 1 tambi&eacute;n tiene muchos recursos<\/span><\/a><span style=\"font-weight: 400;\">. So, together, we are offering much more information to help. <\/span><\/p>\n<p><b>&iquest;Podr&iacute;as describirnos brevemente esta oferta educativa y este nuevo programa y c&oacute;mo podemos utilizarlo para encontrar profesionales de la salud y reenviarlo a amigos que velan por nuestra salud emocional?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Por supuesto. Tenemos una <\/span><a href=\"https:\/\/professional.diabetes.org\/meeting\/other\/mental-health-provider-diabetes-education-program\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">Programa de educaci&oacute;n sobre diabetes y salud mental,<\/span><\/a><span style=\"font-weight: 400;\"> que brinda una oportunidad para que los profesionales de la salud mental reciban una capacitaci&oacute;n integral sobre la diabetes. Por ejemplo, usted puede ser un profesional de la salud mental, un excelente psic&oacute;logo y saber mucho sobre la depresi&oacute;n. Pero eso no significa necesariamente que comprenda la conexi&oacute;n entre la diabetes, la depresi&oacute;n y la salud mental. Es posible que no comprenda qu&eacute; puede hacer para ayudar a una persona, por ejemplo, que tiene mucho miedo a la hipoglucemia. Este programa incluye mucha informaci&oacute;n sobre diferentes aspectos del manejo de la diabetes y lo que puede hacer para ayudar a las personas con diabetes a mejorar su salud mental. Es una gran cantidad de conocimiento basado en investigaciones. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Creo que todos los profesionales de la salud mental deben obtener m&aacute;s informaci&oacute;n y considerar la posibilidad de completar este programa. Cuando lo haya completado, puede agregar su informaci&oacute;n, o la de su colega, a esta lista completa. Luego, las personas con diabetes pueden buscar f&aacute;cilmente profesionales en su &aacute;rea que sepan sobre la diabetes. Sabemos que 34.000 personas viven con diabetes solo en los Estados Unidos. Cuando pensamos en las cifras mundiales, hay millones de personas. Hay demasiadas personas con diabetes y no hay suficientes profesionales de la salud mental que tengan los conocimientos adecuados sobre la diabetes. Hay muchos mitos y conceptos err&oacute;neos sobre la diabetes, como ya se mencion&oacute;. Lamentablemente, si los profesionales no aprenden o no se educan, pueden carecer de la comprensi&oacute;n necesaria para ayudar a las personas con diabetes y comprender la enfermedad en s&iacute;. Ah&iacute; es donde entran en juego programas como este. &iexcl;Pueden ayudar mucho! <\/span><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Nota del editor: Este contenido educativo es posible gracias a la colaboraci&oacute;n ADA x BT1 y se public&oacute; originalmente en espa&ntilde;ol en es.beyondtype1.org . La Dra. Cynthia Mu&ntilde;oz, psic&oacute;loga certificada y profesora adjunta de pediatr&iacute;a cl&iacute;nica, obtuvo su doctorado en psicolog&iacute;a cl&iacute;nica y actualmente trabaja como psic&oacute;loga pedi&aacute;trica en el centro de salud mental del [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":35474,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-35217","resources","type-resources","status-publish","has-post-thumbnail","hentry","content-categories-educacion","content-categories-historia","topics-comunidad","topics-defensa","topics-salud-mental-y","diabetes-types-tipo-1","diabetes-types-tipo-2","tags-mental-health-es","tags-mentalhealth_basics-es","tags-new_home_latest-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salud emocional y diabetes: una conversaci\u00f3n necesaria | Beyond Type 1<\/title>\n<meta name=\"description\" content=\"Cuando nos sentamos con la Dra. Cynthia Mu\u00f1oz, ella comparti\u00f3 consejos y conocimientos esenciales para mejorar su salud emocional con diabetes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salud emocional y diabetes: una conversaci\u00f3n necesaria | Beyond Type 1\" \/>\n<meta property=\"og:description\" content=\"Cuando nos sentamos con la Dra. Cynthia Mu\u00f1oz, ella comparti\u00f3 consejos y conocimientos esenciales para mejorar su salud emocional con diabetes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Type 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beyondtype1\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T16:33:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyondtype1.org\/wp-content\/uploads\/2016\/01\/photo4927170453609491109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1199\" \/>\n\t<meta property=\"og:image:height\" content=\"429\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeyondType1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/\",\"name\":\"Salud emocional y diabetes: una conversaci\u00f3n necesaria | Beyond Type 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/photo4927170453609491109.jpg\",\"datePublished\":\"2016-01-10T18:42:36+00:00\",\"dateModified\":\"2024-12-17T16:33:23+00:00\",\"description\":\"Cuando nos sentamos con la Dra. Cynthia Mu\u00f1oz, ella comparti\u00f3 consejos y conocimientos esenciales para mejorar su salud emocional con diabetes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/photo4927170453609491109.jpg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/photo4927170453609491109.jpg\",\"width\":1199,\"height\":429},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/salud-emocional-y-diabetes-una-conversacion-necesaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salud emocional y diabetes: una conversaci\u00f3n necesaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"name\":\"Beyond Type 1\",\"description\":\"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\",\"name\":\"Beyond Type 1\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"width\":56,\"height\":56,\"caption\":\"Beyond Type 1\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beyondtype1\",\"https:\\\/\\\/x.com\\\/BeyondType1\",\"http:\\\/\\\/instagram.com\\\/BeyondType1\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/BeyondType1\",\"https:\\\/\\\/www.tiktok.com\\\/@beyondtype1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beyond-type1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salud emocional y diabetes: una conversaci\u00f3n necesaria | Beyond Type 1","description":"Cuando nos sentamos con la Dra. Cynthia Mu\u00f1oz, ella comparti\u00f3 consejos y conocimientos esenciales para mejorar su salud emocional con diabetes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/","og_locale":"es_ES","og_type":"article","og_title":"Salud emocional y diabetes: una conversaci\u00f3n necesaria | Beyond Type 1","og_description":"Cuando nos sentamos con la Dra. Cynthia Mu\u00f1oz, ella comparti\u00f3 consejos y conocimientos esenciales para mejorar su salud emocional con diabetes.","og_url":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/","og_site_name":"Beyond Type 1","article_publisher":"https:\/\/www.facebook.com\/beyondtype1","article_modified_time":"2024-12-17T16:33:23+00:00","og_image":[{"width":1199,"height":429,"url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2016\/01\/photo4927170453609491109.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BeyondType1","twitter_misc":{"Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/","url":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/","name":"Salud emocional y diabetes: una conversaci\u00f3n necesaria | Beyond Type 1","isPartOf":{"@id":"https:\/\/beyondtype1.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/#primaryimage"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/#primaryimage"},"thumbnailUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2016\/01\/photo4927170453609491109.jpg","datePublished":"2016-01-10T18:42:36+00:00","dateModified":"2024-12-17T16:33:23+00:00","description":"Cuando nos sentamos con la Dra. Cynthia Mu\u00f1oz, ella comparti\u00f3 consejos y conocimientos esenciales para mejorar su salud emocional con diabetes.","breadcrumb":{"@id":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/#primaryimage","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2016\/01\/photo4927170453609491109.jpg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2016\/01\/photo4927170453609491109.jpg","width":1199,"height":429},{"@type":"BreadcrumbList","@id":"https:\/\/beyondtype1.org\/es\/salud-emocional-y-diabetes-una-conversacion-necesaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondtype1.org\/es\/"},{"@type":"ListItem","position":2,"name":"Salud emocional y diabetes: una conversaci\u00f3n necesaria"}]},{"@type":"WebSite","@id":"https:\/\/beyondtype1.org\/es\/#website","url":"https:\/\/beyondtype1.org\/es\/","name":"Beyond Type 1","description":"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.","publisher":{"@id":"https:\/\/beyondtype1.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondtype1.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/beyondtype1.org\/es\/#organization","name":"Beyond Type 1","url":"https:\/\/beyondtype1.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","width":56,"height":56,"caption":"Beyond Type 1"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondtype1","https:\/\/x.com\/BeyondType1","http:\/\/instagram.com\/BeyondType1\/","https:\/\/www.youtube.com\/c\/BeyondType1","https:\/\/www.tiktok.com\/@beyondtype1","https:\/\/www.linkedin.com\/company\/beyond-type1\/"]}]}},"_links":{"self":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/35217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/comments?post=35217"}],"version-history":[{"count":0,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/35217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media\/35474"}],"wp:attachment":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media?parent=35217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}