{"id":43855,"date":"2026-09-01T22:27:31","date_gmt":"2026-09-01T22:27:31","guid":{"rendered":"https:\/\/beyondtype1.org\/mounjaro-reduce-el-riesgo-de-infarto-y-accidente-cerebrovascular-en-personas-con-diabetes-tipo-2-la-fda-dice-que-si\/"},"modified":"2026-09-01T22:39:49","modified_gmt":"2026-09-01T22:39:49","slug":"mounjaro-riesgo-cardiovascular-diabetes-tipo-2","status":"publish","type":"resources","link":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/","title":{"rendered":"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Si vives con<\/span> <a href=\"https:\/\/beyondtype1.org\/es\/que-es-la-diabetes-tipo-2\/\"><span style=\"font-weight: 400;\">diabetes tipo 2<\/span><\/a>, esta es una noticia importante sobre la salud cardiovascular. Las enfermedades card&iacute;acas son la <a href=\"https:\/\/www.hopkinsmedicine.org\/health\/conditions-and-diseases\/diabetes\/diabetes-and-heart-disease\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">principal causa de muerte en personas con diabetes<\/span><\/a><span style=\"font-weight: 400;\">, y Mounjaro acaba de recibir la aprobaci&oacute;n de la FDA, lo que podr&iacute;a tener un gran impacto en este sentido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El 28 de agosto, la Administraci&oacute;n de Alimentos y Medicamentos (FDA)<\/span> <a href=\"https:\/\/lilly.mediaroom.com\/2026-08-28-FDA-approves-Lillys-Mounjaro-tirzepatide-to-reduce-cardiovascular-risk-in-adults-with-type-2-diabetes\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">aprob&oacute; Mounjaro (tirzepatida)<\/span><\/a><span style=\"font-weight: 400;\">, el agonista dual de los receptores GLP-1\/GIP de Eli Lilly, para reducir el riesgo de eventos cardiovasculares graves, incluyendo muerte, infarto de miocardio no mortal y accidente cerebrovascular no mortal, en adultos con diabetes tipo 2. Las personas con diabetes<\/span> <a href=\"https:\/\/diabetes.org\/about-diabetes\/complications\/cardiovascular-disease\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">tienen el doble de probabilidades<\/span><\/a> <span style=\"font-weight: 400;\">de padecer enfermedades card&iacute;acas o accidentes cerebrovasculares que las personas sin diabetes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mounjaro ya cuenta con la aprobaci&oacute;n de la FDA para mejorar los niveles de glucosa en sangre en adultos y ni&ntilde;os de 10 a&ntilde;os o m&aacute;s con diabetes tipo 2.<\/span> <span style=\"font-weight: 400;\">Esta<\/span> <span style=\"font-weight: 400;\">aprobaci&oacute;n permite que Mounjaro deje de ser un medicamento reservado para<\/span> el manejo de la hemoglobina glicosilada <a href=\"https:\/\/beyondtype1.org\/es\/comprender-tu-a1c\/\"><span style=\"font-weight: 400;\">(A1C)<\/span><\/a> <span style=\"font-weight: 400;\">y el peso para incluir tambi&eacute;n la reducci&oacute;n del riesgo cardiovascular.<\/span><\/p>\n<h3><b>Por qu&eacute; es importante esta aprobaci&oacute;n de la FDA<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Esto es excelente. Hasta<\/span> <a href=\"https:\/\/fnih.org\/our-programs\/vehicle-to-hope-driven-to-cures-mission-to-raise-awareness-and-provide-funding-for-the-research-of-rare-kidney-cancers\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">1 de cada 3 adultos en los EE. UU. con diabetes tipo 2 tiene una enfermedad cardiovascular no detectada<\/span><\/a><span style=\"font-weight: 400;\">. Eso significa que muchas personas podr&iacute;an estar viviendo con una enfermedad cardiovascular no diagnosticada simplemente porque a&uacute;n no han sufrido un ataque card&iacute;aco o un derrame cerebral.<\/span><\/p>\n<h3><b>&iquest;En qu&eacute; se basa la nueva aprobaci&oacute;n de la FDA?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">La nueva aprobaci&oacute;n se basa en los resultados de SURPASS-CVOT, un ensayo cl&iacute;nico hist&oacute;rico sobre resultados cardiovasculares.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">El ensayo cl&iacute;nico sigui&oacute; a m&aacute;s de 13.000 personas en 30 pa&iacute;ses durante m&aacute;s de cuatro a&ntilde;os y medio.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">En lugar de comparar la tirzepatida con un placebo, los investigadores compararon la tirzepatida directamente con<\/span> <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC7540076\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">la dulaglutida, un agonista del receptor GLP-1 que ya ha demostrado tener beneficios cardiovasculares.<\/span><\/a><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mounjaro cumpli&oacute; con los criterios de no inferioridad del ensayo, lo que significa que tuvo un rendimiento al menos tan bueno como el de dulaglutida en la prevenci&oacute;n de eventos cardiovasculares graves.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Los investigadores observaron una tasa un 8 % menor de muerte cardiovascular, infarto o accidente cerebrovascular con tirzepatida en comparaci&oacute;n con dulaglutida.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">&laquo;Para las personas con diabetes tipo 2, la enfermedad card&iacute;aca es la principal causa de muerte, y Mounjaro, el medicamento de marca para la diabetes tipo 2 m&aacute;s recetado en adultos en los EE. UU., ahora les ofrece una forma comprobada de reducir ese riesgo, lo que se suma a la s&oacute;lida base que ya ha construido en cuanto a la hemoglobina glicosilada (A1C) y el peso&raquo;, dijo Kenneth Custer, Ph.D., vicepresidente ejecutivo y presidente de Lilly Cardiometabolic Health. &laquo;Establecimos un est&aacute;ndar m&aacute;s alto al comparar Mounjaro con un medicamento GLP-1 con beneficios cardiovasculares comprobados, lo que refleja la profundidad de la evidencia que Lilly contin&uacute;a acumulando en este campo&raquo;. <\/span><\/p>\n<h3><b>&iquest;Por qu&eacute; la atenci&oacute;n a la diabetes tipo 2 va m&aacute;s all&aacute; del manejo de la glucosa?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Con el tiempo, las investigaciones han demostrado que la diabetes abarca mucho m&aacute;s que la glucosa. La presi&oacute;n arterial, el colesterol, la salud renal, el peso, el nivel de actividad f&iacute;sica,<\/span> <a href=\"https:\/\/beyondtype1.org\/es\/recursos\/\"><span style=\"font-weight: 400;\">la salud mental<\/span><\/a><span style=\"font-weight: 400;\">, la dieta, la salud cardiovascular, el acceso a los medicamentos y la calidad de vida tambi&eacute;n son factores importantes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&laquo;La salud cardiovascular merece atenci&oacute;n durante todo el tratamiento, no solo despu&eacute;s de un evento cardiovascular grave&raquo;, afirm&oacute; el Dr. David A. D&rsquo;Alessio, coautor del estudio y director de la Divisi&oacute;n de Endocrinolog&iacute;a y Metabolismo de la Facultad de Medicina de la Universidad de Duke. &laquo;Si bien gran parte del tratamiento de la diabetes tipo 2 se centra en el control de la glucosa, mitigar el riesgo cardiovascular es fundamental y a menudo se pasa por alto. Esta aprobaci&oacute;n ofrece a los pacientes un medicamento que reduce el riesgo de eventos cardiovasculares y, al mismo tiempo, favorece la salud metab&oacute;lica&raquo;. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El cuidado preventivo del coraz&oacute;n es importante para las personas que a&uacute;n no han sufrido un infarto o un derrame cerebral, pero que aun as&iacute; presentan un riesgo cardiovascular significativo, al igual que todas las personas que viven con diabetes. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mounjaro es ahora el primer y &uacute;nico agonista dual del receptor GLP-1\/GIP con una indicaci&oacute;n aprobada por la FDA para reducir el riesgo de muerte cardiovascular, infarto o accidente cerebrovascular en adultos con diabetes tipo 2 con alto riesgo cardiovascular. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">&iquest;Quieres saber m&aacute;s sobre los GLP-1 y la diabetes? Los GLP-1 no son iguales para todos, y hay mucho que aprender a medida que avanzas. Explora nuestros recursos sobre <\/span><a href=\"https:\/\/beyondtype1.org\/es\/?s=glp1\"><b>GLP-1<\/b><\/a> <span style=\"font-weight: 400;\">para obtener m&aacute;s informaci&oacute;n sobre c&oacute;mo funcionan estos medicamentos, qu&eacute; enfermedades tratan y c&oacute;mo gestionarlos con tu equipo m&eacute;dico.<\/span><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Si vives con diabetes tipo 2, esta es una noticia importante sobre la salud cardiovascular. Las enfermedades card&iacute;acas son la principal causa de muerte en personas con diabetes, y Mounjaro acaba de recibir la aprobaci&oacute;n de la FDA, lo que podr&iacute;a tener un gran impacto en este sentido. El 28 de agosto, la Administraci&oacute;n de [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":36570,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-43855","resources","type-resources","status-publish","has-post-thumbnail","hentry","content-categories-noticias","topics-insulina-y-medicamentos","diabetes-types-tipo-2","tags-diabetes-tipo-2","tags-manejo-de-la-diabetes","tags-manejo-de-la-diabetes-tipo-2","tags-medicamentos-para-la-diabetes","tags-mounjaro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed | Beyond Type 1<\/title>\n<meta name=\"description\" content=\"La FDA aprob\u00f3 Mounjaro para reducir el riesgo cardiovascular en adultos con diabetes tipo 2, lo que supone un hito para las terapias duales de GLP-1\/GIP.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed | Beyond Type 1\" \/>\n<meta property=\"og:description\" content=\"La FDA aprob\u00f3 Mounjaro para reducir el riesgo cardiovascular en adultos con diabetes tipo 2, lo que supone un hito para las terapias duales de GLP-1\/GIP.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyond Type 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beyondtype1\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T22:39:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/04\/BT1-BREAKING-NEWS-2025-02.png\" \/>\n\t<meta property=\"og:image:width\" content=\"5750\" \/>\n\t<meta property=\"og:image:height\" content=\"3234\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeyondType1\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/\",\"name\":\"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed | Beyond Type 1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/BT1-BREAKING-NEWS-2025-02.png\",\"datePublished\":\"2026-09-01T22:27:31+00:00\",\"dateModified\":\"2026-09-01T22:39:49+00:00\",\"description\":\"La FDA aprob\u00f3 Mounjaro para reducir el riesgo cardiovascular en adultos con diabetes tipo 2, lo que supone un hito para las terapias duales de GLP-1\\\/GIP.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/BT1-BREAKING-NEWS-2025-02.png\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/BT1-BREAKING-NEWS-2025-02.png\",\"width\":5750,\"height\":3234,\"caption\":\"It\u2019s Official: MiniMed 780G FDA Approved for Use with Simplera Sensor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"name\":\"Beyond Type 1\",\"description\":\"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#organization\",\"name\":\"Beyond Type 1\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyondtype1.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/header-logo.svg\",\"width\":56,\"height\":56,\"caption\":\"Beyond Type 1\"},\"image\":{\"@id\":\"https:\\\/\\\/beyondtype1.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beyondtype1\",\"https:\\\/\\\/x.com\\\/BeyondType1\",\"http:\\\/\\\/instagram.com\\\/BeyondType1\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/BeyondType1\",\"https:\\\/\\\/www.tiktok.com\\\/@beyondtype1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/beyond-type1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed | Beyond Type 1","description":"La FDA aprob\u00f3 Mounjaro para reducir el riesgo cardiovascular en adultos con diabetes tipo 2, lo que supone un hito para las terapias duales de GLP-1\/GIP.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed | Beyond Type 1","og_description":"La FDA aprob\u00f3 Mounjaro para reducir el riesgo cardiovascular en adultos con diabetes tipo 2, lo que supone un hito para las terapias duales de GLP-1\/GIP.","og_url":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/","og_site_name":"Beyond Type 1","article_publisher":"https:\/\/www.facebook.com\/beyondtype1","article_modified_time":"2026-09-01T22:39:49+00:00","og_image":[{"width":5750,"height":3234,"url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/04\/BT1-BREAKING-NEWS-2025-02.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BeyondType1","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/","url":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/","name":"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed | Beyond Type 1","isPartOf":{"@id":"https:\/\/beyondtype1.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/#primaryimage"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/#primaryimage"},"thumbnailUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/04\/BT1-BREAKING-NEWS-2025-02.png","datePublished":"2026-09-01T22:27:31+00:00","dateModified":"2026-09-01T22:39:49+00:00","description":"La FDA aprob\u00f3 Mounjaro para reducir el riesgo cardiovascular en adultos con diabetes tipo 2, lo que supone un hito para las terapias duales de GLP-1\/GIP.","breadcrumb":{"@id":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/#primaryimage","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/04\/BT1-BREAKING-NEWS-2025-02.png","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/04\/BT1-BREAKING-NEWS-2025-02.png","width":5750,"height":3234,"caption":"It\u2019s Official: MiniMed 780G FDA Approved for Use with Simplera Sensor"},{"@type":"BreadcrumbList","@id":"https:\/\/beyondtype1.org\/es\/mounjaro-riesgo-cardiovascular-diabetes-tipo-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beyondtype1.org\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfMounjaro reduce el riesgo de infarto y accidente cerebrovascular en personas con diabetes tipo 2? La FDA dice que s\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/beyondtype1.org\/es\/#website","url":"https:\/\/beyondtype1.org\/es\/","name":"Beyond Type 1","description":"Beyond Type 1 is the largest diabetes org online, funding advocacy, education and cure research.","publisher":{"@id":"https:\/\/beyondtype1.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyondtype1.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/beyondtype1.org\/es\/#organization","name":"Beyond Type 1","url":"https:\/\/beyondtype1.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","contentUrl":"https:\/\/beyondtype1.org\/wp-content\/uploads\/2025\/08\/header-logo.svg","width":56,"height":56,"caption":"Beyond Type 1"},"image":{"@id":"https:\/\/beyondtype1.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beyondtype1","https:\/\/x.com\/BeyondType1","http:\/\/instagram.com\/BeyondType1\/","https:\/\/www.youtube.com\/c\/BeyondType1","https:\/\/www.tiktok.com\/@beyondtype1","https:\/\/www.linkedin.com\/company\/beyond-type1\/"]}]}},"_links":{"self":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/43855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/types\/resources"}],"author":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/comments?post=43855"}],"version-history":[{"count":3,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/43855\/revisions"}],"predecessor-version":[{"id":43858,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/resources\/43855\/revisions\/43858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media\/36570"}],"wp:attachment":[{"href":"https:\/\/beyondtype1.org\/es\/wp-json\/wp\/v2\/media?parent=43855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}